{"id":2003,"date":"2020-05-06T10:31:48","date_gmt":"2020-05-06T10:31:48","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=633"},"modified":"2024-03-08T10:05:27","modified_gmt":"2024-03-08T09:05:27","slug":"que-es-y-en-que-consiste-el-acero-galvanizado","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/que-es-y-en-que-consiste-el-acero-galvanizado\/","title":{"rendered":"What is galvanized steel and what does it consist of?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">He <a href=\"https:\/\/napoleon-armengol.com\/en\/\">acero galvanizado<\/a> es un acero recubierto con diversas capas de zinc, el cual se ocupa de proteger al acero de la oxidaci\u00f3n y lo convierte en un material mucho m\u00e1s resiste y duradero. El zinc protege de la corrosi\u00f3n al acero y es muy importante su funci\u00f3n para el sector industrial, adem\u00e1s de aportar un gran nivel de brillo y embellecer la apariencia del acero. El zinc ofrece una gran protecci\u00f3n contra la corrosi\u00f3n cat\u00f3dica y el efecto de blindaje, evitando las consecuencias provocadas por ara\u00f1azos o golpes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para fabricar el acero galvanizado, primero se\nfabrican las piezas de acero tales como clavos, tubos, anillas o alambres y\ndespu\u00e9s se aplica la t\u00e9cnica de galvanizaci\u00f3n, que puede ser por inmersi\u00f3n o\nbien por electrogalvanizaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tipos de galvanizado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Galvanizaci\u00f3n por inmersi\u00f3n; En este caso se sumerge la\npieza de acero en el zinc fundido y se genera una reacci\u00f3n qu\u00edmica, en la que\nse forman enlaces constantes entre ambos materiales y, al enfriarse, quedan\ncapas externas s\u00f3lo de zinc, teniendo capas mixtas en el interior y en la parte\nm\u00e1s interna, s\u00f3lo queda el acero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El galvanizado continuo es otro m\u00e9todo, que hace pasar\nhojas o alambres finos de acero a trav\u00e9s del zinc fundido y sigue siendo una inmersi\u00f3n,\npero consiguiendo una capa final m\u00e1s fina de zinc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rociado o pintado con zinc fundido tambi\u00e9n es otra\nopci\u00f3n para conseguir el acero galvanizado, aunque ninguna de estas t\u00e9cnicas es\ntan eficiente como el galvanizado por inmersi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El electrogalvanizado tambi\u00e9n es muy resistente y se\nobtiene una capa de zinc sobre el acero, al mismo tiempo que se forman enlaces\npermanentes y muy fuertes entre ambos metales. Este proceso se hace en fr\u00edo,\nrecubriendo los materiales de acero con una fina capa de zinc, electrol\u00edticamente.\nDespu\u00e9s, se suelda por aquellos puntos de soldadura que no cuentan con la capa\nde zinc para evitar su oxidaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 ventajas presenta el acero\ngalvanizado?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El acero galvanizado tiene muchas ventajas, porque\nhace que la pieza sea m\u00e1s resistente, la protege de la corrosi\u00f3n y la oxidaci\u00f3n\ngracias al zinc, ya que, si no podr\u00eda oxidarse f\u00e1cilmente estando en contacto\ncon el aire, el agua o la humedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El zinc es un metal muy duradero y resistente a golpes\ny rayadas, ofreciendo un aspecto satinado que hace que sea m\u00e1s atractivo y\nvistoso y se utilice, no solo en el sector industrial profesional si no tambi\u00e9n\npara la decoraci\u00f3n de viviendas, que buscan un estilo industrial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n sobre el acero galvanizado o\ncualquier tema relacionado con el sector industrial, te animamos a seguir\nnuestro blog y a visitar nuestra p\u00e1gina web, para consultar cualquier duda que\ntengas o pedir un presupuesto sin compromiso.<\/p>","protected":false},"excerpt":{"rendered":"<p>El acero galvanizado es un acero recubierto con diversas capas de zinc, el cual se ocupa de proteger al acero de la oxidaci\u00f3n y lo convierte en un material mucho m\u00e1s resiste y duradero. El zinc protege de la corrosi\u00f3n al acero y es muy importante su funci\u00f3n para el sector industrial, adem\u00e1s de aportar&#8230;<\/p>","protected":false},"author":1,"featured_media":1833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[119],"tags":[444,445,64],"class_list":["post-2003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnico","tag-acero-galvanizado","tag-galvanizacion","tag-tubo-de-acero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado? - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/que-es-y-en-que-consiste-el-acero-galvanizado\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado? - Armengol\" \/>\n<meta property=\"og:description\" content=\"El acero galvanizado es un acero recubierto con diversas capas de zinc, el cual se ocupa de proteger al acero de la oxidaci\u00f3n y lo convierte en un material mucho m\u00e1s resiste y duradero. El zinc protege de la corrosi\u00f3n al acero y es muy importante su funci\u00f3n para el sector industrial, adem\u00e1s de aportar...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/que-es-y-en-que-consiste-el-acero-galvanizado\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-06T10:31:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T09:05:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado?\",\"datePublished\":\"2020-05-06T10:31:48+00:00\",\"dateModified\":\"2024-03-08T09:05:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/\"},\"wordCount\":506,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/acero-galvanizado-2.jpg\",\"keywords\":[\"acero galvanizado\",\"galvanizaci\u00f3n\",\"tubo de acero\"],\"articleSection\":[\"T\u00e9cnico\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/\",\"name\":\"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado? - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/acero-galvanizado-2.jpg\",\"datePublished\":\"2020-05-06T10:31:48+00:00\",\"dateModified\":\"2024-03-08T09:05:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/acero-galvanizado-2.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/acero-galvanizado-2.jpg\",\"width\":626,\"height\":431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-es-y-en-que-consiste-el-acero-galvanizado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado? - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/que-es-y-en-que-consiste-el-acero-galvanizado\/","og_locale":"en_GB","og_type":"article","og_title":"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado? - Armengol","og_description":"El acero galvanizado es un acero recubierto con diversas capas de zinc, el cual se ocupa de proteger al acero de la oxidaci\u00f3n y lo convierte en un material mucho m\u00e1s resiste y duradero. El zinc protege de la corrosi\u00f3n al acero y es muy importante su funci\u00f3n para el sector industrial, adem\u00e1s de aportar...","og_url":"https:\/\/napoleon-armengol.com\/en\/que-es-y-en-que-consiste-el-acero-galvanizado\/","og_site_name":"Armengol","article_published_time":"2020-05-06T10:31:48+00:00","article_modified_time":"2024-03-08T09:05:27+00:00","og_image":[{"width":626,"height":431,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado?","datePublished":"2020-05-06T10:31:48+00:00","dateModified":"2024-03-08T09:05:27+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/"},"wordCount":506,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg","keywords":["acero galvanizado","galvanizaci\u00f3n","tubo de acero"],"articleSection":["T\u00e9cnico"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/","url":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/","name":"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado? - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg","datePublished":"2020-05-06T10:31:48+00:00","dateModified":"2024-03-08T09:05:27+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg","width":626,"height":431},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/que-es-y-en-que-consiste-el-acero-galvanizado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es y en qu\u00e9 consiste el acero galvanizado?"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":119,"label":"T\u00e9cnico"}],"post_tag":[{"value":444,"label":"acero galvanizado"},{"value":445,"label":"galvanizaci\u00f3n"},{"value":64,"label":"tubo de acero"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/05\/acero-galvanizado-2.jpg",626,431,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":119,"name":"T\u00e9cnico","slug":"tecnico","term_group":0,"term_taxonomy_id":119,"taxonomy":"category","description":"","parent":0,"count":30,"filter":"raw","term_order":"0","cat_ID":119,"category_count":30,"category_description":"","cat_name":"T\u00e9cnico","category_nicename":"tecnico","category_parent":0}],"tag_info":[{"term_id":444,"name":"acero galvanizado","slug":"acero-galvanizado","term_group":0,"term_taxonomy_id":444,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":445,"name":"galvanizaci\u00f3n","slug":"galvanizacion","term_group":0,"term_taxonomy_id":445,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":64,"name":"tubo de acero","slug":"tubo-de-acero","term_group":0,"term_taxonomy_id":64,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=2003"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2003\/revisions"}],"predecessor-version":[{"id":2279,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2003\/revisions\/2279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/1833"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=2003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=2003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=2003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}