{"id":2017,"date":"2020-09-17T08:47:51","date_gmt":"2020-09-17T08:47:51","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=681"},"modified":"2024-01-24T12:20:20","modified_gmt":"2024-01-24T11:20:20","slug":"como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/","title":{"rendered":"How did the Smart City concept arise and what requirements does a city need to be considered smart?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Hay muchos conceptos que forman parte de lo que se\nconsidera ciudad inteligente, pero si hay un requisito obligatorio para ser considerada\nSmart City es el hecho de llevar la sostenibilidad a su m\u00e1xima expresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son entramados urbanos que desarrollan el bienestar de\nlas personas y el medio ambiente, consiguiendo un punto de equilibrio conocido\ncomo sustentabilidad y esto es posible gracias a medidas tecnol\u00f3gicamente\nsostenibles, como puede ser el uso de veh\u00edculos el\u00e9ctricos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 debe tener una Smart City?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una Smart City debe tener un claro compromiso y\nrespeto con el medio ambiente, una clara colaboraci\u00f3n activa entre la\nadministraci\u00f3n p\u00fablica y sus ciudadanos, para fomentar la cohesi\u00f3n social, una\nintegraci\u00f3n claramente tecnol\u00f3gica para el funcionamiento de sus\ninfraestructuras y los servicios de transporte, una transparencia y apertura\nabsoluta de sus datos, una eficiente gesti\u00f3n econ\u00f3mica y tambi\u00e9n de todos los\nrecursos materiales, una planificaci\u00f3n urbana coherente y sostenible, una completa\naccesibilidad universal y una movilidad urbana sostenible, un uso de las TIC\nque permita conseguir el bienestar de los habitantes y del planeta, una clara\ninnovaci\u00f3n tecnol\u00f3gica y arquitect\u00f3nica que permita aumentar la calidad de vida\nde las personas y del planeta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es posible que en 2050 un 70% de la poblaci\u00f3n viva en\nciudades, de modo que si se da esta masificaci\u00f3n en zonas urbanas es necesario\nque estas tomen partida y construyan ciudades verdes y sostenibles, adaptadas a\nlas necesidades y exigencias urgentes del planeta y la salud de las personas\nque habitan en \u00e9l. Las emisiones nocivas y excesivas a la atm\u00f3sfera, el abastecimiento\nenerg\u00e9tico y un uso poco optimizado de las tecnolog\u00edas puede convertirse en el peor\nenemigo para todos y as\u00ed es como surge esta idea de Smart City, para transformar\nlos n\u00facleos urbanos y solventar estos problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de conseguir ciudades sostenibles\necon\u00f3mica, social y medioambientalmente nacen las ciudades inteligentes o Smart\nCities, que son transformaciones de las ciudades urbanas a trav\u00e9s de la\naplicaci\u00f3n de tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n con el objetivo\nde proveerlas de infraestructuras que puedan garantizar:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Un desarrollo sostenible<\/li><li>Un incremento de la calidad de vida de los ciudadanos<\/li><li>Una mayor eficacia de los recursos disponibles<\/li><li>Una participaci\u00f3n ciudadana activa<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Durante las siguientes d\u00e9cadas que est\u00e1n por llegar,\nlos n\u00facleos urbanos tienen que afrontar un n\u00famero creciente de problemas\nligados a este hecho como es; <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El abastecimiento energ\u00e9tico<\/li><li>Las emisiones de Co2<\/li><li>La planificaci\u00f3n del tr\u00e1fico automovil\u00edstico<\/li><li>La provisi\u00f3n de bienes y materias primas<\/li><li>La prestaci\u00f3n de servicios sanitarios y tambi\u00e9n de seguridad\na quienes residan en estos centros de poblaci\u00f3n<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de estos cambios conseguiremos que la Smart\nCity no parezca el sue\u00f1o inalcanzable, sino un objetivo a corto plazo para\ntodas las ciudades del mundo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hay muchos conceptos que forman parte de lo que se considera ciudad inteligente, pero si hay un requisito obligatorio para ser considerada Smart City es el hecho de llevar la sostenibilidad a su m\u00e1xima expresi\u00f3n. Son entramados urbanos que desarrollan el bienestar de las personas y el medio ambiente, consiguiendo un punto de equilibrio conocido&#8230;<\/p>","protected":false},"author":1,"featured_media":1846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[69],"tags":[461,437,149,306,359,462],"class_list":["post-2017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-abastecimiento-energetico","tag-ciudades-inteligentes","tag-energias-renovables","tag-smart-city","tag-sostenibilidad","tag-tic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente? - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente? - Armengol\" \/>\n<meta property=\"og:description\" content=\"Hay muchos conceptos que forman parte de lo que se considera ciudad inteligente, pero si hay un requisito obligatorio para ser considerada Smart City es el hecho de llevar la sostenibilidad a su m\u00e1xima expresi\u00f3n. Son entramados urbanos que desarrollan el bienestar de las personas y el medio ambiente, consiguiendo un punto de equilibrio conocido...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-17T08:47:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T11:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente?\",\"datePublished\":\"2020-09-17T08:47:51+00:00\",\"dateModified\":\"2024-01-24T11:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/\"},\"wordCount\":515,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/smart-city.jpg\",\"keywords\":[\"abastecimiento energ\u00e9tico\",\"ciudades inteligentes\",\"energ\u00edas renovables\",\"Smart City\",\"sostenibilidad\",\"TIC\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/\",\"name\":\"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente? - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/smart-city.jpg\",\"datePublished\":\"2020-09-17T08:47:51+00:00\",\"dateModified\":\"2024-01-24T11:20:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/smart-city.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/smart-city.jpg\",\"width\":626,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente? - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/","og_locale":"en_GB","og_type":"article","og_title":"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente? - Armengol","og_description":"Hay muchos conceptos que forman parte de lo que se considera ciudad inteligente, pero si hay un requisito obligatorio para ser considerada Smart City es el hecho de llevar la sostenibilidad a su m\u00e1xima expresi\u00f3n. Son entramados urbanos que desarrollan el bienestar de las personas y el medio ambiente, consiguiendo un punto de equilibrio conocido...","og_url":"https:\/\/napoleon-armengol.com\/en\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/","og_site_name":"Armengol","article_published_time":"2020-09-17T08:47:51+00:00","article_modified_time":"2024-01-24T11:20:20+00:00","og_image":[{"width":626,"height":417,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente?","datePublished":"2020-09-17T08:47:51+00:00","dateModified":"2024-01-24T11:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/"},"wordCount":515,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg","keywords":["abastecimiento energ\u00e9tico","ciudades inteligentes","energ\u00edas renovables","Smart City","sostenibilidad","TIC"],"articleSection":["Econom\u00eda"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/","url":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/","name":"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente? - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg","datePublished":"2020-09-17T08:47:51+00:00","dateModified":"2024-01-24T11:20:20+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg","width":626,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/como-surge-el-concepto-smart-city-y-que-requisitos-necesita-una-ciudad-para-ser-considerada-inteligente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo surge el concepto Smart City y qu\u00e9 requisitos necesita una ciudad para ser considerada inteligente?"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":69,"label":"Econom\u00eda"}],"post_tag":[{"value":461,"label":"abastecimiento energ\u00e9tico"},{"value":437,"label":"ciudades inteligentes"},{"value":149,"label":"energ\u00edas renovables"},{"value":306,"label":"Smart City"},{"value":359,"label":"sostenibilidad"},{"value":462,"label":"TIC"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/09\/smart-city.jpg",626,417,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":69,"name":"Econom\u00eda","slug":"economia","term_group":0,"term_taxonomy_id":69,"taxonomy":"category","description":"","parent":0,"count":57,"filter":"raw","term_order":"0","cat_ID":69,"category_count":57,"category_description":"","cat_name":"Econom\u00eda","category_nicename":"economia","category_parent":0}],"tag_info":[{"term_id":461,"name":"abastecimiento energ\u00e9tico","slug":"abastecimiento-energetico","term_group":0,"term_taxonomy_id":461,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":437,"name":"ciudades inteligentes","slug":"ciudades-inteligentes","term_group":0,"term_taxonomy_id":437,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw","term_order":"0"},{"term_id":149,"name":"energ\u00edas renovables","slug":"energias-renovables","term_group":0,"term_taxonomy_id":149,"taxonomy":"post_tag","description":"","parent":0,"count":30,"filter":"raw","term_order":"0"},{"term_id":306,"name":"Smart City","slug":"smart-city","term_group":0,"term_taxonomy_id":306,"taxonomy":"post_tag","description":"","parent":0,"count":8,"filter":"raw","term_order":"0"},{"term_id":359,"name":"sostenibilidad","slug":"sostenibilidad","term_group":0,"term_taxonomy_id":359,"taxonomy":"post_tag","description":"","parent":0,"count":5,"filter":"raw","term_order":"0"},{"term_id":462,"name":"TIC","slug":"tic","term_group":0,"term_taxonomy_id":462,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=2017"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2017\/revisions"}],"predecessor-version":[{"id":2265,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2017\/revisions\/2265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/1846"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=2017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=2017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=2017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}