{"id":207,"date":"2018-11-29T11:30:46","date_gmt":"2018-11-29T11:30:46","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=207"},"modified":"2024-01-24T12:27:42","modified_gmt":"2024-01-24T11:27:42","slug":"aviones-y-eficiencia-energetica","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/aviones-y-eficiencia-energetica\/","title":{"rendered":"AIRPLANES AND ENERGY EFFICIENCY"},"content":{"rendered":"<p style=\"text-align: justify;\">Bienvenidos un d\u00eda m\u00e1s a nuestro blog de Napole\u00f3n Armengol, hoy tambi\u00e9n les trajimos un tema interesante y es sobre las aviones y <strong>energy efficiency<\/strong>. Para empezar, les decimos que la gesti\u00f3n del tr\u00e1fico a\u00e9reo no es muy eficiente.<\/p>\n<p style=\"text-align: justify;\">Hay oportunidades de <strong>energy efficiency<\/strong> mediante la revisi\u00f3n y optimizaci\u00f3n de gestiones de flotas, la log\u00edstica de vuelo y el uso de corrientes de chorro en el cielo.<\/p>\n<p style=\"text-align: justify;\">Reunir y verificar los datos almacenados en el registro de vuelo automatizado puede abrir nuevos caminos para que las compa\u00f1\u00edas a\u00e9reas administren y operen mejor sus flotas para economizar combustible y costos.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">OPTIMIZAR RUTAS, PLANIFICACI\u00d3N Y MANTENIMIENTO DE AERONAVES<\/h3>\n<p style=\"text-align: justify;\">Tradicionalmente, los aviones se han aproximado a una pista de aterrizaje bajando en vez de hacer un descenso constante y terso.<\/p>\n<p style=\"text-align: justify;\">Esto ha significado que, en cada paso, los pilotos han tenido que ajustar el empuje de los motores. Actualmente la tecnolog\u00eda deja que las compa\u00f1\u00edas a\u00e9reas puedan trabajar con el control del tr\u00e1fico a\u00e9reo para crear una bajada mucho m\u00e1s suave a la pasarela, mejorando as\u00ed la <strong>energy efficiency<\/strong> del combustible.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-211 alignright\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920-1-300x201.jpg\" alt=\"\" width=\"336\" height=\"225\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920-1-300x201.jpg 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920-1-768x514.jpg 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920-1.jpg 960w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/p>\n<p style=\"text-align: justify;\">El ajuste de la sincronizaci\u00f3n de los vuelos tambi\u00e9n deja las aeronaves a poder lograr una mejor <strong>energy efficiency <\/strong>del combustible mediante la reducci\u00f3n de la durada de los per\u00edodos de espera en vuelo.<\/p>\n<p style=\"text-align: justify;\">El combustible se puede tambi\u00e9n economizar usando apenas un motor por vuelo de avi\u00f3n ahorra 430.000 litros de combustible cada a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">A VECES VOLAR CON LAS CORRIENTES DE CHORRO Y OTRA VECES NO<\/h3>\n<p style=\"text-align: justify;\">La ubicaci\u00f3n de las corrientes de chorro es esencial en la aviaci\u00f3n. A parte de reducir el tiempo de vuelo tambi\u00e9n economiza combustible. Pero la verdad es que no siempre es as\u00ed ya que, en Australia, los vuelos de oeste a este pueden tomar beneficio de las corrientes de chorro, mientras que los vuelos de este a oeste necesitan enviar esa corriente tanto como se pueda.<\/p>\n<p style=\"text-align: justify;\">Existe el potencial de mejorar la <strong>energy efficiency<\/strong> de combustible para los vuelos internacionales incrementando la calidad de la previsi\u00f3n de las corrientes de chorro, en concreto sobre las zonas oce\u00e1nicas y apenas pobladas.<\/p>\n<p style=\"text-align: justify;\">Se espera que las mejoras en la log\u00edstica de la aviaci\u00f3n, en concreto de la tecnolog\u00eda de la informaci\u00f3n, economizan un 5-10% del combustible.<\/p>\n<p style=\"text-align: justify;\">Las aeronaves m\u00e1s adelantadas cuentan actualmente con la tecnolog\u00eda que permite optimizar las rutas de vuelo en tiempo real en respuesta a los cambios en los patrones atmosf\u00e9ricos.<\/p>\n<p style=\"text-align: justify;\">El redireccionamiento en vuelo puede economizar combustible significativo en los vuelos internacionales, donde los vientos de nivel m\u00e1s alto, las corrientes de chorro y otros par\u00e1metros atmosf\u00e9ricos pueden cambiar r\u00e1pidamente.<\/p>\n<p style=\"text-align: justify;\">Estas tecnolog\u00edas de log\u00edstica de vuelo en tiempo real, se pueden usar cuando se alzan las restricciones del espacio a\u00e9reo.<\/p>\n<p>&nbsp;<\/p>\n<p>fuente de la imagen destacada\u00a0http:\/\/capitalradio.es\/la-aeronautica\/?doing_wp_cron=1543490950.6968500614166259765625<\/p>","protected":false},"excerpt":{"rendered":"<p>Bienvenidos un d\u00eda m\u00e1s a nuestro blog de Napole\u00f3n Armengol, hoy tambi\u00e9n les trajimos un tema interesante y es sobre las aviones y eficiencia energ\u00e9tica. Para empezar, les decimos que la gesti\u00f3n del tr\u00e1fico a\u00e9reo no es muy eficiente. Hay oportunidades de eficiencia energ\u00e9tica mediante la revisi\u00f3n y optimizaci\u00f3n de gestiones de flotas, la log\u00edstica&#8230;<\/p>","protected":false},"author":1,"featured_media":208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[70],"tags":[96,133,145,165,146,110,111,102],"class_list":["post-207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energias-renovables","tag-ahorro-energetico","tag-descenso","tag-electricidad","tag-empresas","tag-energia","tag-medio-ambiente","tag-movilidad-sostenible","tag-soluciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVIONES Y EFICIENCIA ENERG\u00c9TICA - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/aviones-y-eficiencia-energetica\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVIONES Y EFICIENCIA ENERG\u00c9TICA - Armengol\" \/>\n<meta property=\"og:description\" content=\"Bienvenidos un d\u00eda m\u00e1s a nuestro blog de Napole\u00f3n Armengol, hoy tambi\u00e9n les trajimos un tema interesante y es sobre las aviones y eficiencia energ\u00e9tica. Para empezar, les decimos que la gesti\u00f3n del tr\u00e1fico a\u00e9reo no es muy eficiente. Hay oportunidades de eficiencia energ\u00e9tica mediante la revisi\u00f3n y optimizaci\u00f3n de gestiones de flotas, la log\u00edstica...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/aviones-y-eficiencia-energetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-29T11:30:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T11:27:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"AVIONES Y EFICIENCIA ENERG\u00c9TICA\",\"datePublished\":\"2018-11-29T11:30:46+00:00\",\"dateModified\":\"2024-01-24T11:27:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/\"},\"wordCount\":516,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/plane-170272_1920.jpg\",\"keywords\":[\"ahorro energ\u00e9tico\",\"descenso\",\"electricidad\",\"empresas\",\"energ\u00eda\",\"medio ambiente\",\"movilidad sostenible\",\"soluciones\"],\"articleSection\":[\"Energ\u00edas renovables\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/\",\"name\":\"AVIONES Y EFICIENCIA ENERG\u00c9TICA - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/plane-170272_1920.jpg\",\"datePublished\":\"2018-11-29T11:30:46+00:00\",\"dateModified\":\"2024-01-24T11:27:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/plane-170272_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/plane-170272_1920.jpg\",\"width\":1920,\"height\":1258},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/aviones-y-eficiencia-energetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVIONES Y EFICIENCIA ENERG\u00c9TICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVIONES Y EFICIENCIA ENERG\u00c9TICA - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/aviones-y-eficiencia-energetica\/","og_locale":"en_GB","og_type":"article","og_title":"AVIONES Y EFICIENCIA ENERG\u00c9TICA - Armengol","og_description":"Bienvenidos un d\u00eda m\u00e1s a nuestro blog de Napole\u00f3n Armengol, hoy tambi\u00e9n les trajimos un tema interesante y es sobre las aviones y eficiencia energ\u00e9tica. Para empezar, les decimos que la gesti\u00f3n del tr\u00e1fico a\u00e9reo no es muy eficiente. Hay oportunidades de eficiencia energ\u00e9tica mediante la revisi\u00f3n y optimizaci\u00f3n de gestiones de flotas, la log\u00edstica...","og_url":"https:\/\/napoleon-armengol.com\/en\/aviones-y-eficiencia-energetica\/","og_site_name":"Armengol","article_published_time":"2018-11-29T11:30:46+00:00","article_modified_time":"2024-01-24T11:27:42+00:00","og_image":[{"width":1920,"height":1258,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"AVIONES Y EFICIENCIA ENERG\u00c9TICA","datePublished":"2018-11-29T11:30:46+00:00","dateModified":"2024-01-24T11:27:42+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/"},"wordCount":516,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920.jpg","keywords":["ahorro energ\u00e9tico","descenso","electricidad","empresas","energ\u00eda","medio ambiente","movilidad sostenible","soluciones"],"articleSection":["Energ\u00edas renovables"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/","url":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/","name":"AVIONES Y EFICIENCIA ENERG\u00c9TICA - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920.jpg","datePublished":"2018-11-29T11:30:46+00:00","dateModified":"2024-01-24T11:27:42+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920.jpg","width":1920,"height":1258},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/aviones-y-eficiencia-energetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"AVIONES Y EFICIENCIA ENERG\u00c9TICA"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":70,"label":"Energ\u00edas renovables"}],"post_tag":[{"value":96,"label":"ahorro energ\u00e9tico"},{"value":133,"label":"descenso"},{"value":145,"label":"electricidad"},{"value":165,"label":"empresas"},{"value":146,"label":"energ\u00eda"},{"value":110,"label":"medio ambiente"},{"value":111,"label":"movilidad sostenible"},{"value":102,"label":"soluciones"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/plane-170272_1920-1024x671.jpg",1024,671,true],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":70,"name":"Energ\u00edas renovables","slug":"energias-renovables","term_group":0,"term_taxonomy_id":70,"taxonomy":"category","description":"","parent":0,"count":13,"filter":"raw","term_order":"0","cat_ID":70,"category_count":13,"category_description":"","cat_name":"Energ\u00edas renovables","category_nicename":"energias-renovables","category_parent":0}],"tag_info":[{"term_id":96,"name":"ahorro energ\u00e9tico","slug":"ahorro-energetico","term_group":0,"term_taxonomy_id":96,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":133,"name":"descenso","slug":"descenso","term_group":0,"term_taxonomy_id":133,"taxonomy":"post_tag","description":"","parent":0,"count":12,"filter":"raw","term_order":"0"},{"term_id":145,"name":"electricidad","slug":"electricidad","term_group":0,"term_taxonomy_id":145,"taxonomy":"post_tag","description":"","parent":0,"count":14,"filter":"raw","term_order":"0"},{"term_id":165,"name":"empresas","slug":"empresas","term_group":0,"term_taxonomy_id":165,"taxonomy":"post_tag","description":"","parent":0,"count":13,"filter":"raw","term_order":"0"},{"term_id":146,"name":"energ\u00eda","slug":"energia","term_group":0,"term_taxonomy_id":146,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw","term_order":"0"},{"term_id":110,"name":"medio ambiente","slug":"medio-ambiente","term_group":0,"term_taxonomy_id":110,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":111,"name":"movilidad sostenible","slug":"movilidad-sostenible","term_group":0,"term_taxonomy_id":111,"taxonomy":"post_tag","description":"","parent":0,"count":31,"filter":"raw","term_order":"0"},{"term_id":102,"name":"soluciones","slug":"soluciones","term_group":0,"term_taxonomy_id":102,"taxonomy":"post_tag","description":"","parent":0,"count":32,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":2358,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/207\/revisions\/2358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/208"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}