{"id":2814,"date":"2024-05-02T14:20:54","date_gmt":"2024-05-02T12:20:54","guid":{"rendered":"https:\/\/napoleon-armengol.com\/?p=2814"},"modified":"2024-05-03T12:05:11","modified_gmt":"2024-05-03T10:05:11","slug":"tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/","title":{"rendered":"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Soluciones profesionales para <\/strong><strong>la protecci\u00f3n de cables en <\/strong><strong>instalaciones <\/strong><strong>el\u00e9ctricas en locales<\/strong><strong> industriales, comerciales y <\/strong><strong>de servicio<\/strong><strong> o residenciales<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La selecci\u00f3n del tipo de tubo adecuado es fundamental en cualquier proyecto de instalaci\u00f3n, ya sea industrial, comercial y de servicio o residencial. Los <a href=\"https:\/\/napoleon-armengol.com\/en\/product-category\/sistemas-de-tubo-rigido\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tubes for electrical installations<\/strong><\/a><strong> <\/strong>se clasifican en diversas categor\u00edas, seg\u00fan sus propiedades f\u00edsicas y aplicaciones espec\u00edficas, y deben tenerse en cuenta en el momento de la instalaci\u00f3n.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/02\/CURVA-FLEXIBLE-METALICA-ROS.png\" alt=\"CURVA FLEXIBLE META\u0301LICA ROS\" class=\"wp-image-1060\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/02\/CURVA-FLEXIBLE-METALICA-ROS.png 1000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/02\/CURVA-FLEXIBLE-METALICA-ROS-300x300.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/02\/CURVA-FLEXIBLE-METALICA-ROS-150x150.png 150w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/02\/CURVA-FLEXIBLE-METALICA-ROS-768x768.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/02\/CURVA-FLEXIBLE-METALICA-ROS-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tubos r\u00edgidos: aplicaciones espec\u00edficas<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Son tubos que no pueden curvarse y solamente pueden hacerlo con ayuda de medios mec\u00e1nicos con o sin tratamiento especial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las canalizaciones superficiales, los tubos deben ser preferentemente r\u00edgidos. Sus caracter\u00edsticas m\u00ednimas se indican en la ITC-BT-21 y el cumplimiento de estas caracter\u00edsticas se realiza seg\u00fan los ensayos indicados en la norma IEC EN 61386-21.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su uso es perfecto en instalaciones donde sea necesario adem\u00e1s de guiar el cable protegerlo mediante una envolvente. Proporcionan un adecuado nivel de protecci\u00f3n contra impactos y compresiones mec\u00e1nicas, requeridos en funci\u00f3n del tipo de instalaci\u00f3n superficial.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/CURVA-90o-EG-ROS.png\" alt=\"tubo de instalaci\u00f3n el\u00e9ctrica\" class=\"wp-image-1045\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/CURVA-90o-EG-ROS.png 1000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/CURVA-90o-EG-ROS-300x300.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/CURVA-90o-EG-ROS-150x150.png 150w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/CURVA-90o-EG-ROS-768x768.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/CURVA-90o-EG-ROS-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tubos curvables: flexibilidad limitada con una curvatura \u00fanica<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tubos cuya caracter\u00edstica principal es la de poder curvarse a mano con una fuerza razonable, y que no est\u00e1n destinados a una flexi\u00f3n frecuente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tipo de tubos conservan la forma curvada una vez instalados y son utilizados en canalizaciones empotradas en obra. Habitualmente se instalan por ejemplo en paredes, techos, falsos techos y huecos de la construcci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tubos flexibles: destinados a flexi\u00f3n frecuente&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los tubos flexibles pueden doblarse a mano aplicando una fuerza razonablemente peque\u00f1a y est\u00e1n destinados a flexiones frecuentes a lo largo de su vida \u00fatil. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los tubos flexibles de poliamida 6 de Napole\u00f3n Armengol est\u00e1n especialmente dise\u00f1ados para ser usados en la industria, conectando tanto m\u00e1quinas fijas con cuadros de instrumentos m\u00f3viles como elementos robotizados y automatizados que est\u00e9n continuamente en movimiento.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/TUBO-RIGIDO-SS-AISI-304-ARMET-2.png\" alt=\"TUBO RI\u0301GIDO SS AISI 304 ARMET\" class=\"wp-image-1037\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/TUBO-RIGIDO-SS-AISI-304-ARMET-2.png 1000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/TUBO-RIGIDO-SS-AISI-304-ARMET-2-300x300.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/TUBO-RIGIDO-SS-AISI-304-ARMET-2-150x150.png 150w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/TUBO-RIGIDO-SS-AISI-304-ARMET-2-768x768.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/TUBO-RIGIDO-SS-AISI-304-ARMET-2-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Selecci\u00f3n de tubos para instalaciones el\u00e9ctricas<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La selecci\u00f3n de los <strong>tubes for electrical installations<\/strong> va a depender de las necesidades espec\u00edficas de cada proyecto y de las condiciones de instalaci\u00f3n. Comprender las diferencias entre los tubos r\u00edgidos, curvables y flexibles es esencial para garantizar una instalaci\u00f3n eficiente y duradera.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al elegir los tubos adecuados para cada aplicaci\u00f3n, se pueden evitar problemas futuros y garantizar un rendimiento \u00f3ptimo del sistema. La selecci\u00f3n adecuada de <strong>tubes for electrical installations<\/strong> aumenta la protecci\u00f3n de los cables contra da\u00f1os mec\u00e1nicos y condiciones ambientales adversas, como tambi\u00e9n garantizan la integridad de las propias instalaciones.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La mejor selecci\u00f3n de tubos para instalaciones el\u00e9ctricas en Napole\u00f3n Armengol<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La elecci\u00f3n de tubos adecuados asegura la fiabilidad y durabilidad a largo plazo de las instalaciones, reduciendo la necesidad de mantenimiento y reparaciones costosas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Napole\u00f3n Armengol podemos ofrecerte la m\u00e1xima seguridad en <strong>tubes for electrical installations<\/strong> y la m\u00e1xima especializaci\u00f3n en sistemas de tubo r\u00edgido para tuber\u00edas, as\u00ed como en material toma tierra.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Soluciones profesionales para la protecci\u00f3n de cables en instalaciones el\u00e9ctricas en locales industriales, comerciales y de servicio o residenciales&nbsp; La selecci\u00f3n del tipo de tubo adecuado es fundamental en cualquier proyecto de instalaci\u00f3n, ya sea industrial, comercial y de servicio o residencial. Los tubos para instalaciones el\u00e9ctricas se clasifican en diversas categor\u00edas, seg\u00fan sus propiedades&#8230;<\/p>","protected":false},"author":1,"featured_media":1820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[63],"tags":[],"class_list":["post-2814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tipos de tubos y usos; r\u00edgidos, curvables y flexibles - Armengol<\/title>\n<meta name=\"description\" content=\"La selecci\u00f3n del tubo adecuado es esencial en proyectos industriales, comerciales y residenciales. Descubre la variedad y caracter\u00edsticas esenciales aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles - Armengol\" \/>\n<meta property=\"og:description\" content=\"La selecci\u00f3n del tubo adecuado es esencial en proyectos industriales, comerciales y residenciales. Descubre la variedad y caracter\u00edsticas esenciales aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T12:20:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T10:05:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles\",\"datePublished\":\"2024-05-02T12:20:54+00:00\",\"dateModified\":\"2024-05-03T10:05:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/\"},\"wordCount\":553,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/fabricacion-tubos-de-acero-1.jpg\",\"articleSection\":[\"Productos\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/\",\"name\":\"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/fabricacion-tubos-de-acero-1.jpg\",\"datePublished\":\"2024-05-02T12:20:54+00:00\",\"dateModified\":\"2024-05-03T10:05:11+00:00\",\"description\":\"La selecci\u00f3n del tubo adecuado es esencial en proyectos industriales, comerciales y residenciales. Descubre la variedad y caracter\u00edsticas esenciales aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/fabricacion-tubos-de-acero-1.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/fabricacion-tubos-de-acero-1.jpg\",\"width\":626,\"height\":442,\"caption\":\"fabricaci\u00f3n tubos de acero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles - Armengol","description":"La selecci\u00f3n del tubo adecuado es esencial en proyectos industriales, comerciales y residenciales. Descubre la variedad y caracter\u00edsticas esenciales aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/","og_locale":"en_GB","og_type":"article","og_title":"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles - Armengol","og_description":"La selecci\u00f3n del tubo adecuado es esencial en proyectos industriales, comerciales y residenciales. Descubre la variedad y caracter\u00edsticas esenciales aqu\u00ed.","og_url":"https:\/\/napoleon-armengol.com\/en\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/","og_site_name":"Armengol","article_published_time":"2024-05-02T12:20:54+00:00","article_modified_time":"2024-05-03T10:05:11+00:00","og_image":[{"width":626,"height":442,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles","datePublished":"2024-05-02T12:20:54+00:00","dateModified":"2024-05-03T10:05:11+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/"},"wordCount":553,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg","articleSection":["Productos"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/","url":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/","name":"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg","datePublished":"2024-05-02T12:20:54+00:00","dateModified":"2024-05-03T10:05:11+00:00","description":"La selecci\u00f3n del tubo adecuado es esencial en proyectos industriales, comerciales y residenciales. Descubre la variedad y caracter\u00edsticas esenciales aqu\u00ed.","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg","width":626,"height":442,"caption":"fabricaci\u00f3n tubos de acero"},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/tipos-de-tubos-y-usos-rigidos-curvables-y-flexibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Tipos de tubos y usos; r\u00edgidos, curvables y flexibles"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":63,"label":"Productos"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/fabricacion-tubos-de-acero-1.jpg",626,442,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":63,"name":"Productos","slug":"productos","term_group":0,"term_taxonomy_id":63,"taxonomy":"category","description":"","parent":0,"count":34,"filter":"raw","term_order":"0","cat_ID":63,"category_count":34,"category_description":"","cat_name":"Productos","category_nicename":"productos","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=2814"}],"version-history":[{"count":3,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2814\/revisions"}],"predecessor-version":[{"id":2833,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2814\/revisions\/2833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/1820"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=2814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=2814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=2814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}