{"id":2897,"date":"2024-07-02T15:34:12","date_gmt":"2024-07-02T13:34:12","guid":{"rendered":"https:\/\/napoleon-armengol.com\/?p=2897"},"modified":"2024-06-27T15:42:50","modified_gmt":"2024-06-27T13:42:50","slug":"que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/","title":{"rendered":"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Rigid tube systems <\/strong><strong>met\u00e1licos<\/strong><strong>; electro galvanizado, galvanizado en caliente y acero inoxidable<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">The <a href=\"https:\/\/napoleon-armengol.com\/en\/product-category\/sistemas-de-tubo-rigido\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tubos para cables el\u00e9ctricos de exterior<\/strong><\/a> deben proporcionar una protecci\u00f3n adecuada del cableado, ya que est\u00e1 expuesto a condiciones ambientales adversas. Estos tubos est\u00e1n dise\u00f1ados espec\u00edficamente para resistir la exposici\u00f3n a la intemperie, la humedad, los rayos UV y otros factores externos que podr\u00edan comprometer la integridad y el rendimiento del cableado el\u00e9ctrico. Los <strong>tubos para la protecci\u00f3n de cables el\u00e9ctricos instalados en el exterior<\/strong> proporcionan una barrera f\u00edsica que protege los cables contra la humedad, la corrosi\u00f3n, los impactos mec\u00e1nicos y otros peligros ambientales, garantizando as\u00ed un suministro el\u00e9ctrico seguro y confiable. Desde temperaturas extremadamente altas hasta temperaturas extremadamente fr\u00edas, estos tubos deben mantener su integridad estructural y protegen eficazmente el cableado el\u00e9ctrico en todo momento.\u00a0\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/06\/TUBO-RIGIDO-HD-ARMET.png\" alt=\"tubo r\u00edgido para sistemas de cableado\" class=\"wp-image-1926\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/06\/TUBO-RIGIDO-HD-ARMET.png 1000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/06\/TUBO-RIGIDO-HD-ARMET-300x300.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/06\/TUBO-RIGIDO-HD-ARMET-150x150.png 150w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/06\/TUBO-RIGIDO-HD-ARMET-768x768.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/06\/TUBO-RIGIDO-HD-ARMET-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tubo r\u00edgido electro galvanizado<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estos sistemas ofrecen una resistencia a la corrosi\u00f3n tanto en el interior como en el exterior, con un grado de protecci\u00f3n de 2 sobre 4 seg\u00fan la norma IEC 61386 (protecci\u00f3n media). Son ideales para entornos que requieren cumplir con los requisitos de las ITC-BT-28 y ITC-BT-29, donde se necesita protecci\u00f3n contra impactos mec\u00e1nicos o riesgos de explosi\u00f3n.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/06\/tubo-de-acero-inoxidable1.png\" alt=\"selecci\u00f3n de tubos de acero\" class=\"wp-image-1008\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/06\/tubo-de-acero-inoxidable1.png 940w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/06\/tubo-de-acero-inoxidable1-300x251.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/06\/tubo-de-acero-inoxidable1-768x644.png 768w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tubo r\u00edgido galvanizado en caliente<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este tubo presenta caracter\u00edsticas similares al tubo electro galvanizado, pero cuenta con una resistencia a la corrosi\u00f3n a\u00fan mayor, alcanzando el grado 4 seg\u00fan la norma IEC 61386 (protecci\u00f3n muy alta). Es ideal para instalaciones que requieren una protecci\u00f3n superior contra la corrosi\u00f3n, y cumple con los est\u00e1ndares establecidos por las ITC-BT-30 y 31.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tubo r\u00edgido inoxidable<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con una resistencia a la corrosi\u00f3n a\u00fan m\u00e1s elevada, el tubo r\u00edgido inoxidable es capaz de cumplir con los exigentes est\u00e1ndares de la industria alimentaria, manteniendo al mismo tiempo una resistencia mec\u00e1nica \u00f3ptima. Este tipo de tubo es adecuado para aplicaciones que requieren una protecci\u00f3n superior contra la corrosi\u00f3n y cumple con las ITC-BT-30 y 31.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada tipo de material y recubrimiento tiene un \u00e1mbito de uso recomendado, lo que permite seleccionar la opci\u00f3n m\u00e1s adecuada para cada aplicaci\u00f3n. En Napole\u00f3n Armengol fabricamos Sistemas de tubo r\u00edgido para entornos y sectores espec\u00edficos, para conseguir la m\u00e1xima protecci\u00f3n del cableado el\u00e9ctrico, tanto en entornos interiores como exteriores.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1-1024x1024.jpg\" alt=\"tubo r\u00edgido\" class=\"wp-image-1084\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1-1024x1024.jpg 1024w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1-300x300.jpg 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1-150x150.jpg 150w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1-768x768.jpg 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1-100x100.jpg 100w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/06\/010TROM025-1-1200x1200-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para obtener m\u00e1s informaci\u00f3n sobre los <strong>tubos para cables el\u00e9ctricos instalados en el exterior<\/strong> y sobre todos los sistemas de tubo r\u00edgido que podemos ofrecerte, no dudes en contactar con nosotros. Nuestro equipo puede proporcionarte asesoramiento personalizado y garantizar el \u00e9xito de tus proyectos el\u00e9ctricos.\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Sistemas de tubo r\u00edgido met\u00e1licos; electro galvanizado, galvanizado en caliente y acero inoxidable&nbsp; Los tubos para cables el\u00e9ctricos de exterior deben proporcionar una protecci\u00f3n adecuada del cableado, ya que est\u00e1 expuesto a condiciones ambientales adversas. Estos tubos est\u00e1n dise\u00f1ados espec\u00edficamente para resistir la exposici\u00f3n a la intemperie, la humedad, los rayos UV y otros factores&#8230;<\/p>","protected":false},"author":1,"featured_media":221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[63],"tags":[493],"class_list":["post-2897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productos","tag-tubos-para-cables-electricos-de-exterior"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0 - Armengol<\/title>\n<meta name=\"description\" content=\"Los tubos met\u00e1licos r\u00edgidos electro galvanizados, galvanizados en caliente y de acero inoxidable ofrecen la mayor protecci\u00f3n contra impactos mec\u00e1nicos en instalaciones exteriores de cableado el\u00e9ctrico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0 - Armengol\" \/>\n<meta property=\"og:description\" content=\"Los tubos met\u00e1licos r\u00edgidos electro galvanizados, galvanizados en caliente y de acero inoxidable ofrecen la mayor protecci\u00f3n contra impactos mec\u00e1nicos en instalaciones exteriores de cableado el\u00e9ctrico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T13:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0\",\"datePublished\":\"2024-07-02T13:34:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/tubo-acero-cilindrico_28549-554.jpg\",\"keywords\":[\"tubos para cables el\u00e9ctricos de exterior\"],\"articleSection\":[\"Productos\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/\",\"name\":\"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0 - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/tubo-acero-cilindrico_28549-554.jpg\",\"datePublished\":\"2024-07-02T13:34:12+00:00\",\"description\":\"Los tubos met\u00e1licos r\u00edgidos electro galvanizados, galvanizados en caliente y de acero inoxidable ofrecen la mayor protecci\u00f3n contra impactos mec\u00e1nicos en instalaciones exteriores de cableado el\u00e9ctrico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/tubo-acero-cilindrico_28549-554.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/tubo-acero-cilindrico_28549-554.jpg\",\"width\":626,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0 - Armengol","description":"Los tubos met\u00e1licos r\u00edgidos electro galvanizados, galvanizados en caliente y de acero inoxidable ofrecen la mayor protecci\u00f3n contra impactos mec\u00e1nicos en instalaciones exteriores de cableado el\u00e9ctrico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/","og_locale":"en_GB","og_type":"article","og_title":"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0 - Armengol","og_description":"Los tubos met\u00e1licos r\u00edgidos electro galvanizados, galvanizados en caliente y de acero inoxidable ofrecen la mayor protecci\u00f3n contra impactos mec\u00e1nicos en instalaciones exteriores de cableado el\u00e9ctrico.","og_url":"https:\/\/napoleon-armengol.com\/en\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/","og_site_name":"Armengol","article_published_time":"2024-07-02T13:34:12+00:00","og_image":[{"width":626,"height":417,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0","datePublished":"2024-07-02T13:34:12+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/"},"wordCount":482,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg","keywords":["tubos para cables el\u00e9ctricos de exterior"],"articleSection":["Productos"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/","url":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/","name":"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0 - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg","datePublished":"2024-07-02T13:34:12+00:00","description":"Los tubos met\u00e1licos r\u00edgidos electro galvanizados, galvanizados en caliente y de acero inoxidable ofrecen la mayor protecci\u00f3n contra impactos mec\u00e1nicos en instalaciones exteriores de cableado el\u00e9ctrico.","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg","width":626,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/que-tipo-de-tubos-para-instalaciones-al-exterior-ofrecen-una-mayor-proteccion-contra-los-impactos-mecanicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 tipo de tubos para instalaciones al exterior ofrecen una mayor protecci\u00f3n contra los impactos mec\u00e1nicos?\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":63,"label":"Productos"}],"post_tag":[{"value":493,"label":"tubos para cables el\u00e9ctricos de exterior"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/11\/tubo-acero-cilindrico_28549-554.jpg",626,417,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":63,"name":"Productos","slug":"productos","term_group":0,"term_taxonomy_id":63,"taxonomy":"category","description":"","parent":0,"count":34,"filter":"raw","term_order":"0","cat_ID":63,"category_count":34,"category_description":"","cat_name":"Productos","category_nicename":"productos","category_parent":0}],"tag_info":[{"term_id":493,"name":"tubos para cables el\u00e9ctricos de exterior","slug":"tubos-para-cables-electricos-de-exterior","term_group":0,"term_taxonomy_id":493,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=2897"}],"version-history":[{"count":2,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2897\/revisions"}],"predecessor-version":[{"id":2899,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/2897\/revisions\/2899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/221"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=2897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=2897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=2897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}