{"id":446,"date":"2019-07-12T06:35:09","date_gmt":"2019-07-12T06:35:09","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=446"},"modified":"2024-03-05T12:18:12","modified_gmt":"2024-03-05T11:18:12","slug":"las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/","title":{"rendered":"Renewable energies need more political support to achieve greater stability"},"content":{"rendered":"<p class=\"wp-block-paragraph\">REN\n21, una organizaci\u00f3n internacional, ha publicado el informe <a href=\"http:\/\/www.ren21.net\/gsr-2019\/\">Renewables\n2019 Global Status<\/a> en el que se\nexigen pol\u00edticas m\u00e1s ambiciosas en energ\u00edas renovables para conseguir una mayor\nestabilidad en este sector, ya que actualmente las energ\u00edas alternativas se\nocupan de suministrar m\u00e1s de un 26% de la producci\u00f3n mundial de electricidad.\nEsto quiere decir que para poder mantener este sistema es necesario obtener m\u00e1s\napoyo econ\u00f3mico y pol\u00edtico, para conseguir un sistema de energ\u00eda m\u00e1s sostenible\nque el que existe actualmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este\ndocumento asegura que la falta de pol\u00edticas ambiciosas para impulsar la\ndescarbonizaci\u00f3n en los sectores del transporte, calor y fr\u00edo tiene como\nconsecuencia que los pa\u00edses no puedan maximizar sus beneficios de la transici\u00f3n\npara su poblaci\u00f3n, incluyendo la seguridad energ\u00e9tica y una mayor calidad del\naire. Esto podr\u00eda solucionarse, seg\u00fan aseguran en el informe, eliminando los\nsubsidios a los combustibles f\u00f3siles, que generan energ\u00eda perjudicial para el\nplaneta y para la poblaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-2.jpg\" alt=\"\" class=\"wp-image-448\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La energ\u00eda solar fotovoltaica y la\nenerg\u00eda e\u00f3lica son las dos fuentes principales del sector el\u00e9ctrico<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El documento, que analiza\nel estatus mundial de las energ\u00edas renovables, asegura que la capacidad\nel\u00e9ctrica&nbsp;<strong>renovable instalada\nsuper\u00f3, durante 2018, a la creada por la energ\u00eda nuclear y los combustibles\nf\u00f3siles combinados<\/strong><strong>, <\/strong>por\ncuarto a\u00f1o consecutivo. Solo la energ\u00eda solar fotovoltaica sum\u00f3 100 GW,\nsuficiente como para cumplir con el 25% de la demanda de electricidad francesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n\nse destaca que las ciudades&nbsp; han mostrado\nclaras se\u00f1ales de ser fuertes impulsoras para el despliegue de la energ\u00eda\nrenovable, adoptando algunos de los objetivos&nbsp;\nma\u00b4s ambiciosos para las energ\u00edas renovables a nivel mundial. Este\ninforme revela tambi\u00e9n que la energ\u00eda e\u00f3lica y la energ\u00eda solar fotovoltaica\nson las dos tendencias principales en lo que se refiere al sector el\u00e9ctrico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe\nun gran desequilibrio entre los sectores energ\u00e9ticos, ya que las energ\u00edas renovables suministran m\u00e1s\ndel 26% de la electricidad global pero solo proporcionan el 10% de la energ\u00eda\nutilizada para calor y fr\u00edo, y poco m\u00e1s del 3% para el transporte. Esta\ndesproporci\u00f3n se debe, en parte, a un apoyo insuficiente de las pol\u00edticas\ndestinadas a este tema. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>A\u00fan\nqueda hueco para el optimismo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque falta apoyo, cabe decir que se han\nimplementado iniciativas importantes en muchos sectores, como pueden ser los\nbiocarburantes sostenibles en el sector del transporte, as\u00ed como los veh\u00edculos\nel\u00e9ctricos y las pol\u00edticas de consumo de combustible, que permiten disminuir la\ndependencia de los combustibles f\u00f3siles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las pol\u00edticas del sector del fr\u00edo y del calor\ncuentan con c\u00f3digos de energ\u00eda para la construcci\u00f3n, as\u00ed como incentivos y\nreglamentaci\u00f3n y estrategias para la fijaci\u00f3n de precios del carbono, pero a\u00fan\nno se utilizan plenamente.<\/p>","protected":false},"excerpt":{"rendered":"<p>REN 21, una organizaci\u00f3n internacional, ha publicado el informe Renewables 2019 Global Status en el que se exigen pol\u00edticas m\u00e1s ambiciosas en energ\u00edas renovables para conseguir una mayor estabilidad en este sector, ya que actualmente las energ\u00edas alternativas se ocupan de suministrar m\u00e1s de un 26% de la producci\u00f3n mundial de electricidad. Esto quiere decir&#8230;<\/p>","protected":false},"author":1,"featured_media":447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[70],"tags":[375,376,149,110,359],"class_list":["post-446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energias-renovables","tag-energia-alternativa","tag-energia-limpia","tag-energias-renovables","tag-medio-ambiente","tag-sostenibilidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad - Armengol\" \/>\n<meta property=\"og:description\" content=\"REN 21, una organizaci\u00f3n internacional, ha publicado el informe Renewables 2019 Global Status en el que se exigen pol\u00edticas m\u00e1s ambiciosas en energ\u00edas renovables para conseguir una mayor estabilidad en este sector, ya que actualmente las energ\u00edas alternativas se ocupan de suministrar m\u00e1s de un 26% de la producci\u00f3n mundial de electricidad. Esto quiere decir...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-12T06:35:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T11:18:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad\",\"datePublished\":\"2019-07-12T06:35:09+00:00\",\"dateModified\":\"2024-03-05T11:18:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/energias-renovables-1.jpg\",\"keywords\":[\"energ\u00eda alternativa\",\"energ\u00eda limpia\",\"energ\u00edas renovables\",\"medio ambiente\",\"sostenibilidad\"],\"articleSection\":[\"Energ\u00edas renovables\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/\",\"name\":\"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/energias-renovables-1.jpg\",\"datePublished\":\"2019-07-12T06:35:09+00:00\",\"dateModified\":\"2024-03-05T11:18:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/energias-renovables-1.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/energias-renovables-1.jpg\",\"width\":960,\"height\":639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/","og_locale":"en_GB","og_type":"article","og_title":"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad - Armengol","og_description":"REN 21, una organizaci\u00f3n internacional, ha publicado el informe Renewables 2019 Global Status en el que se exigen pol\u00edticas m\u00e1s ambiciosas en energ\u00edas renovables para conseguir una mayor estabilidad en este sector, ya que actualmente las energ\u00edas alternativas se ocupan de suministrar m\u00e1s de un 26% de la producci\u00f3n mundial de electricidad. Esto quiere decir...","og_url":"https:\/\/napoleon-armengol.com\/en\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/","og_site_name":"Armengol","article_published_time":"2019-07-12T06:35:09+00:00","article_modified_time":"2024-03-05T11:18:12+00:00","og_image":[{"width":960,"height":639,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad","datePublished":"2019-07-12T06:35:09+00:00","dateModified":"2024-03-05T11:18:12+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/"},"wordCount":513,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg","keywords":["energ\u00eda alternativa","energ\u00eda limpia","energ\u00edas renovables","medio ambiente","sostenibilidad"],"articleSection":["Energ\u00edas renovables"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/","url":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/","name":"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg","datePublished":"2019-07-12T06:35:09+00:00","dateModified":"2024-03-05T11:18:12+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg","width":960,"height":639},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/las-energias-renovables-necesitan-mas-apoyo-politico-para-conseguir-una-mayor-estabilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Las energ\u00edas renovables necesitan m\u00e1s apoyo pol\u00edtico para conseguir una mayor estabilidad"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":70,"label":"Energ\u00edas renovables"}],"post_tag":[{"value":375,"label":"energ\u00eda alternativa"},{"value":376,"label":"energ\u00eda limpia"},{"value":149,"label":"energ\u00edas renovables"},{"value":110,"label":"medio ambiente"},{"value":359,"label":"sostenibilidad"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/07\/energias-renovables-1.jpg",960,639,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":70,"name":"Energ\u00edas renovables","slug":"energias-renovables","term_group":0,"term_taxonomy_id":70,"taxonomy":"category","description":"","parent":0,"count":13,"filter":"raw","term_order":"0","cat_ID":70,"category_count":13,"category_description":"","cat_name":"Energ\u00edas renovables","category_nicename":"energias-renovables","category_parent":0}],"tag_info":[{"term_id":375,"name":"energ\u00eda alternativa","slug":"energia-alternativa","term_group":0,"term_taxonomy_id":375,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":376,"name":"energ\u00eda limpia","slug":"energia-limpia","term_group":0,"term_taxonomy_id":376,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","term_order":"0"},{"term_id":149,"name":"energ\u00edas renovables","slug":"energias-renovables","term_group":0,"term_taxonomy_id":149,"taxonomy":"post_tag","description":"","parent":0,"count":30,"filter":"raw","term_order":"0"},{"term_id":110,"name":"medio ambiente","slug":"medio-ambiente","term_group":0,"term_taxonomy_id":110,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":359,"name":"sostenibilidad","slug":"sostenibilidad","term_group":0,"term_taxonomy_id":359,"taxonomy":"post_tag","description":"","parent":0,"count":5,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=446"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/446\/revisions"}],"predecessor-version":[{"id":2316,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/446\/revisions\/2316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/447"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}