{"id":64,"date":"2018-05-18T07:18:09","date_gmt":"2018-05-18T07:18:09","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=64"},"modified":"2024-03-04T10:32:02","modified_gmt":"2024-03-04T09:32:02","slug":"vem2018-acercara-los-coches-electricos-al-publico-madrileno","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/en\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/","title":{"rendered":"VEM2018 will bring electric cars closer to the Madrid public"},"content":{"rendered":"<p align=\"justify\">VEM es una exposici\u00f3n que pretende dar a conocer los veh\u00edculos el\u00e9ctricos a la ciudadan\u00eda madrile\u00f1a, as\u00ed como ofrecer la oportunidad de probarlos y descubrir personalmente cada una de sus ventajas. Esta exposici\u00f3n tendr\u00e1 lugar en la Plaza Col\u00f3n de Madrid desde el d\u00eda 1 al 3 de Junio de 2018.<\/p>\n<p align=\"justify\">Esta exposici\u00f3n la organiza AEDIVE desde el a\u00f1o 2015 junto con el Ayuntamiento de Madrid, la colaboraci\u00f3n de del portal movilidadelectrica.com y el impulso de la Comunidad de Madrid. El objetivo principal de esta feria es acercar la movilidad de cero emisiones tanto a particulares como a profesionales p\u00fablicos y privados.<\/p>\n<p align=\"justify\">Como patrocinadores platino, esta feria cuenta con las marcas de coche Nissan y Renault, mientras que en la categor\u00eda de patrocinadores oro encontramos las empresas BMW, COUP, Endesa, Fen\u00ede energ\u00eda, Gesternova energ\u00eda, Iberdrola, Citro\u00ebn y Peugeot. La mayor\u00eda de estas empresas tendr\u00e1n su lugar de exposici\u00f3n en la feria con tal de dar a conocer tanto sus productos como sus iniciativas de veh\u00edculos de movilidad de cero emisiones.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/VEM-2017.jpg\" alt=\"\" width=\"700\" height=\"355\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/VEM-2017.jpg 700w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/VEM-2017-300x152.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p align=\"justify\">En las pasadas ediciones de esta feria, tuvieron una media de 12.000 visitantes que fueron a la Plaza Col\u00f3n de Madrid a probar en un entorno urbano, los distintos coches el\u00e9ctricos que ofrec\u00eda la feria. Adem\u00e1s, las empresas expositoras ofrecen toda la informaci\u00f3n necesaria para conocer el funcionamiento y ventajas de este tipo de movilidad.<\/p>\n<p align=\"justify\">En esta edici\u00f3n de VEM podremos encontrar todo tipo de empresas que expondr\u00e1n sus veh\u00edculos el\u00e9ctricos, puntos de carga, o servicios de sharing de bici, moto y coche. Todos estos productos y servicios estar\u00e1n a disposici\u00f3n de todas aquellas personas que quieran probarlos y disfrutar personalmente de la experiencia de probarlos.<\/p>\n<h2>AEDIVE: la asociaci\u00f3n organizadora<\/h2>\n<p align=\"justify\">AEDIVE es la Asociaci\u00f3n Empresarial para el Desarrollo e Impulso del Veh\u00edculo El\u00e9ctrico, se cre\u00f3 en abril del 2010 y desde entonces ha tenido una larga trayectoria y representaci\u00f3n por parte de sus empresas, las cuales son miembros de pleno derecho-fabricantes y distribuidores de veh\u00edculos el\u00e9ctricos y de puntos de recarga.<\/p>\n<p align=\"justify\">Adem\u00e1s del papel que tiene esta asociaci\u00f3n a nivel nacional de la industria y tecnolog\u00eda vinculadas al veh\u00edculo el\u00e9ctrico, tambi\u00e9n forma parte de asociaciones tanto nacionales como internacionales que le aportan m\u00e1s valor y relevancia en su papel como frente en movilidad el\u00e9ctrica, siendo miembro de la Plataforma Tecnol\u00f3gica Espa\u00f1ola de Automoci\u00f3n y Movilidad Move2Future.<\/p>","protected":false},"excerpt":{"rendered":"<p>VEM es una exposici\u00f3n que pretende dar a conocer los veh\u00edculos el\u00e9ctricos a la ciudadan\u00eda madrile\u00f1a, as\u00ed como ofrecer la oportunidad de probarlos y descubrir personalmente cada una de sus ventajas. Esta exposici\u00f3n tendr\u00e1 lugar en la Plaza Col\u00f3n de Madrid desde el d\u00eda 1 al 3 de Junio de 2018. Esta exposici\u00f3n la organiza&#8230;<\/p>","protected":false},"author":1,"featured_media":66,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[68],"tags":[104,96,105,95,97,106,107,108,109,110,100,111,112,102,113,114,115],"class_list":["post-64","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coche-eletrico","tag-aedive","tag-ahorro-energetico","tag-asiciacion","tag-coche-electrico","tag-coches-electricos","tag-contaminacion","tag-evento","tag-feria","tag-madrid","tag-medio-ambiente","tag-movilidad-electrica","tag-movilidad-sostenible","tag-probar-coche","tag-soluciones","tag-sostenible","tag-vehiculos","tag-vehiculos-electricos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o - Armengol\" \/>\n<meta property=\"og:description\" content=\"VEM es una exposici\u00f3n que pretende dar a conocer los veh\u00edculos el\u00e9ctricos a la ciudadan\u00eda madrile\u00f1a, as\u00ed como ofrecer la oportunidad de probarlos y descubrir personalmente cada una de sus ventajas. Esta exposici\u00f3n tendr\u00e1 lugar en la Plaza Col\u00f3n de Madrid desde el d\u00eda 1 al 3 de Junio de 2018. Esta exposici\u00f3n la organiza...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-18T07:18:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-04T09:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o\",\"datePublished\":\"2018-05-18T07:18:09+00:00\",\"dateModified\":\"2024-03-04T09:32:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/\"},\"wordCount\":443,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg\",\"keywords\":[\"AEDIVE\",\"ahorro energ\u00e9tico\",\"asiciaci\u00f3n\",\"Coche el\u00e9ctrico\",\"coches el\u00e9ctricos\",\"contaminaci\u00f3n\",\"evento\",\"feria\",\"Madrid\",\"medio ambiente\",\"movilidad el\u00e9ctrica\",\"movilidad sostenible\",\"probar coche\",\"soluciones\",\"sostenible\",\"veh\u00edculos\",\"veh\u00edculos el\u00e9ctricos\"],\"articleSection\":[\"Coche el\u00e9trico\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/\",\"name\":\"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg\",\"datePublished\":\"2018-05-18T07:18:09+00:00\",\"dateModified\":\"2024-03-04T09:32:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/en\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/","og_locale":"en_GB","og_type":"article","og_title":"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o - Armengol","og_description":"VEM es una exposici\u00f3n que pretende dar a conocer los veh\u00edculos el\u00e9ctricos a la ciudadan\u00eda madrile\u00f1a, as\u00ed como ofrecer la oportunidad de probarlos y descubrir personalmente cada una de sus ventajas. Esta exposici\u00f3n tendr\u00e1 lugar en la Plaza Col\u00f3n de Madrid desde el d\u00eda 1 al 3 de Junio de 2018. Esta exposici\u00f3n la organiza...","og_url":"https:\/\/napoleon-armengol.com\/en\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/","og_site_name":"Armengol","article_published_time":"2018-05-18T07:18:09+00:00","article_modified_time":"2024-03-04T09:32:02+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o","datePublished":"2018-05-18T07:18:09+00:00","dateModified":"2024-03-04T09:32:02+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/"},"wordCount":443,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg","keywords":["AEDIVE","ahorro energ\u00e9tico","asiciaci\u00f3n","Coche el\u00e9ctrico","coches el\u00e9ctricos","contaminaci\u00f3n","evento","feria","Madrid","medio ambiente","movilidad el\u00e9ctrica","movilidad sostenible","probar coche","soluciones","sostenible","veh\u00edculos","veh\u00edculos el\u00e9ctricos"],"articleSection":["Coche el\u00e9trico"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/","url":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/","name":"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg","datePublished":"2018-05-18T07:18:09+00:00","dateModified":"2024-03-04T09:32:02+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/vem2018-acercara-los-coches-electricos-al-publico-madrileno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"VEM2018 acercar\u00e1 los coches el\u00e9ctricos al p\u00fablico madrile\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":68,"label":"Coche el\u00e9trico"}],"post_tag":[{"value":104,"label":"AEDIVE"},{"value":96,"label":"ahorro energ\u00e9tico"},{"value":105,"label":"asiciaci\u00f3n"},{"value":95,"label":"Coche el\u00e9ctrico"},{"value":97,"label":"coches el\u00e9ctricos"},{"value":106,"label":"contaminaci\u00f3n"},{"value":107,"label":"evento"},{"value":108,"label":"feria"},{"value":109,"label":"Madrid"},{"value":110,"label":"medio ambiente"},{"value":100,"label":"movilidad el\u00e9ctrica"},{"value":111,"label":"movilidad sostenible"},{"value":112,"label":"probar coche"},{"value":102,"label":"soluciones"},{"value":113,"label":"sostenible"},{"value":114,"label":"veh\u00edculos"},{"value":115,"label":"veh\u00edculos el\u00e9ctricos"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/05\/La_plaza_de_Colon_acoge_la_Feria_del_Vehiculo_Electrico_VEM_2017_este_fin_de_semana_04-1024x683.jpg",1024,683,true],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/en\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":68,"name":"Coche el\u00e9trico","slug":"coche-eletrico","term_group":0,"term_taxonomy_id":68,"taxonomy":"category","description":"","parent":0,"count":63,"filter":"raw","term_order":"0","cat_ID":68,"category_count":63,"category_description":"","cat_name":"Coche el\u00e9trico","category_nicename":"coche-eletrico","category_parent":0}],"tag_info":[{"term_id":104,"name":"AEDIVE","slug":"aedive","term_group":0,"term_taxonomy_id":104,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","term_order":"0"},{"term_id":96,"name":"ahorro energ\u00e9tico","slug":"ahorro-energetico","term_group":0,"term_taxonomy_id":96,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":105,"name":"asiciaci\u00f3n","slug":"asiciacion","term_group":0,"term_taxonomy_id":105,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":95,"name":"Coche el\u00e9ctrico","slug":"coche-electrico","term_group":0,"term_taxonomy_id":95,"taxonomy":"post_tag","description":"","parent":0,"count":45,"filter":"raw","term_order":"0"},{"term_id":97,"name":"coches el\u00e9ctricos","slug":"coches-electricos","term_group":0,"term_taxonomy_id":97,"taxonomy":"post_tag","description":"","parent":0,"count":25,"filter":"raw","term_order":"0"},{"term_id":106,"name":"contaminaci\u00f3n","slug":"contaminacion","term_group":0,"term_taxonomy_id":106,"taxonomy":"post_tag","description":"","parent":0,"count":19,"filter":"raw","term_order":"0"},{"term_id":107,"name":"evento","slug":"evento","term_group":0,"term_taxonomy_id":107,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":108,"name":"feria","slug":"feria","term_group":0,"term_taxonomy_id":108,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","term_order":"0"},{"term_id":109,"name":"Madrid","slug":"madrid","term_group":0,"term_taxonomy_id":109,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":110,"name":"medio ambiente","slug":"medio-ambiente","term_group":0,"term_taxonomy_id":110,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":100,"name":"movilidad el\u00e9ctrica","slug":"movilidad-electrica","term_group":0,"term_taxonomy_id":100,"taxonomy":"post_tag","description":"","parent":0,"count":41,"filter":"raw","term_order":"0"},{"term_id":111,"name":"movilidad sostenible","slug":"movilidad-sostenible","term_group":0,"term_taxonomy_id":111,"taxonomy":"post_tag","description":"","parent":0,"count":31,"filter":"raw","term_order":"0"},{"term_id":112,"name":"probar coche","slug":"probar-coche","term_group":0,"term_taxonomy_id":112,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":102,"name":"soluciones","slug":"soluciones","term_group":0,"term_taxonomy_id":102,"taxonomy":"post_tag","description":"","parent":0,"count":32,"filter":"raw","term_order":"0"},{"term_id":113,"name":"sostenible","slug":"sostenible","term_group":0,"term_taxonomy_id":113,"taxonomy":"post_tag","description":"","parent":0,"count":15,"filter":"raw","term_order":"0"},{"term_id":114,"name":"veh\u00edculos","slug":"vehiculos","term_group":0,"term_taxonomy_id":114,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw","term_order":"0"},{"term_id":115,"name":"veh\u00edculos el\u00e9ctricos","slug":"vehiculos-electricos","term_group":0,"term_taxonomy_id":115,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":2383,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/posts\/64\/revisions\/2383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/66"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}