{"id":834,"date":"2023-05-17T08:22:06","date_gmt":"2023-05-17T08:22:06","guid":{"rendered":"http:\/\/napoleon-armengol.com\/?post_type=product&#038;p=834"},"modified":"2023-11-29T07:25:01","modified_gmt":"2023-11-29T07:25:01","slug":"manguito-hd-armet","status":"publish","type":"product","link":"https:\/\/napoleon-armengol.com\/en\/product\/manguito-hd-armet\/","title":{"rendered":"HD ARMET SLEEVE"},"content":{"rendered":"<p>TECHNICAL SPECIFICATIONS ACCORDING TO IEC 61386-21 STANDARD<\/p>\n<p><strong>Code<\/strong>: 555711544010.<br \/>\n<strong>Use temperature<\/strong>: -45\u00baC +400\u00baC.<br \/>\n<strong>Compression resistance<\/strong>: &gt; 4,000 N.<br \/>\n<strong>Impact resistence<\/strong>: &gt; 20J at -45\u00baC.<br \/>\n<strong>Corrosion resistance of pipe systems<\/strong>: High.<br \/>\n<strong>No propagator of the flame.<\/strong><\/p>\n<p><strong>Material<\/strong>: DC03 quality cold rolled strap according to UNE EN 10130 standard.<br \/>\n<strong>Finish<\/strong>: Hot dip galvanized, passivated and UNIFIX sealed<sup>TM<\/sup>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-408\" src=\"http:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/ce-2.png\" alt=\"\" width=\"181\" height=\"65\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/ce-2.png 500w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/ce-2-300x108.png 300w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>DIMENSIONS ACCORDING TO IEC 60423 STANDARD<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-692\" src=\"http:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET-1.png\" alt=\"\" width=\"2000\" height=\"662\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET-1.png 2000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET-1-300x99.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET-1-1024x339.png 1024w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET-1-768x254.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET-1-1536x508.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>","protected":false},"featured_media":610,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"product_cat":[15,17,54],"product_tag":[],"class_list":["post-834","product","type-product","status-publish","has-post-thumbnail","product_cat-sistemas-de-tubo-rigido","product_cat-sistema-de-tubo-rigido-galvanizado-en-caliente","product_cat-accesorios-tubo-rigido-hd","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANGUITO HD ARMET - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/product\/manguito-hd-armet\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANGUITO HD ARMET - Armengol\" \/>\n<meta property=\"og:description\" content=\"DIMENSIONES SEG\u00daN NORMA IEC 60423\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/product\/manguito-hd-armet\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T07:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/\",\"name\":\"MANGUITO HD ARMET - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MANGUITO-HD-ARMET.png\",\"datePublished\":\"2023-05-17T08:22:06+00:00\",\"dateModified\":\"2023-11-29T07:25:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MANGUITO-HD-ARMET.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MANGUITO-HD-ARMET.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/manguito-hd-armet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MANGUITO HD ARMET\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANGUITO HD ARMET - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/product\/manguito-hd-armet\/","og_locale":"en_GB","og_type":"article","og_title":"MANGUITO HD ARMET - Armengol","og_description":"DIMENSIONES SEG\u00daN NORMA IEC 60423","og_url":"https:\/\/napoleon-armengol.com\/en\/product\/manguito-hd-armet\/","og_site_name":"Armengol","article_modified_time":"2023-11-29T07:25:01+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/","url":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/","name":"MANGUITO HD ARMET - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET.png","datePublished":"2023-05-17T08:22:06+00:00","dateModified":"2023-11-29T07:25:01+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/producto\/manguito-hd-armet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/napoleon-armengol.com\/productos\/"},{"@type":"ListItem","position":3,"name":"MANGUITO HD ARMET"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":15,"label":"Sistemas de tubo r\u00edgido"},{"value":17,"label":"Sistema de tubo r\u00edgido Galvanizado en caliente"},{"value":54,"label":"Accesorios tubo r\u00edgido HD"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MANGUITO-HD-ARMET.png",1000,1000,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product\/834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/comments?post=834"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product\/834\/revisions"}],"predecessor-version":[{"id":1616,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product\/834\/revisions\/1616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/media?parent=834"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product_cat?post=834"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product_tag?post=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}