{"id":31,"count":1,"description":"","link":"https:\/\/napoleon-armengol.com\/en\/product-category\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/","name":"Caja de derivaci\u00f3n met\u00e1licas inoxidables","slug":"caja-de-derivacion-metalicas-inoxidables","taxonomy":"product_cat","parent":30,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caja de derivaci\u00f3n met\u00e1licas inoxidables archivos - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/en\/product-category\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caja de derivaci\u00f3n met\u00e1licas inoxidables archivos - Armengol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/en\/product-category\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/categoria-producto\\\/cajas-de-derivacion\\\/cajas-derivacion-metalicas\\\/caja-de-derivacion-metalicas-inoxidables\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/categoria-producto\\\/cajas-de-derivacion\\\/cajas-derivacion-metalicas\\\/caja-de-derivacion-metalicas-inoxidables\\\/\",\"name\":\"Caja de derivaci\u00f3n met\u00e1licas inoxidables archivos - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/categoria-producto\\\/cajas-de-derivacion\\\/cajas-derivacion-metalicas\\\/caja-de-derivacion-metalicas-inoxidables\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/categoria-producto\\\/cajas-de-derivacion\\\/cajas-derivacion-metalicas\\\/caja-de-derivacion-metalicas-inoxidables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cajas de derivaci\u00f3n\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/categoria-producto\\\/cajas-de-derivacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cajas derivaci\u00f3n met\u00e1licas\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/categoria-producto\\\/cajas-de-derivacion\\\/cajas-derivacion-metalicas\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Caja de derivaci\u00f3n met\u00e1licas inoxidables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caja de derivaci\u00f3n met\u00e1licas inoxidables archivos - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/en\/product-category\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/","og_locale":"en_GB","og_type":"article","og_title":"Caja de derivaci\u00f3n met\u00e1licas inoxidables archivos - Armengol","og_url":"https:\/\/napoleon-armengol.com\/en\/product-category\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/","og_site_name":"Armengol","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/napoleon-armengol.com\/categoria-producto\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/","url":"https:\/\/napoleon-armengol.com\/categoria-producto\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/","name":"Caja de derivaci\u00f3n met\u00e1licas inoxidables archivos - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/categoria-producto\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/categoria-producto\/cajas-de-derivacion\/cajas-derivacion-metalicas\/caja-de-derivacion-metalicas-inoxidables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Cajas de derivaci\u00f3n","item":"https:\/\/napoleon-armengol.com\/categoria-producto\/cajas-de-derivacion\/"},{"@type":"ListItem","position":3,"name":"Cajas derivaci\u00f3n met\u00e1licas","item":"https:\/\/napoleon-armengol.com\/categoria-producto\/cajas-de-derivacion\/cajas-derivacion-metalicas\/"},{"@type":"ListItem","position":4,"name":"Caja de derivaci\u00f3n met\u00e1licas inoxidables"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product_cat\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product_cat\/30"}],"wp:post_type":[{"href":"https:\/\/napoleon-armengol.com\/en\/wp-json\/wp\/v2\/product?product_cat=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}