{"id":10,"date":"2017-11-30T12:51:38","date_gmt":"2017-11-30T12:51:38","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=10"},"modified":"2024-01-24T13:10:36","modified_gmt":"2024-01-24T12:10:36","slug":"plan-de-apoyo-a-la-movilidad-alternativa","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/plan-de-apoyo-a-la-movilidad-alternativa\/","title":{"rendered":"Plan d&#039;accompagnement des mobilit\u00e9s alternatives"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El Ministerio de Energ\u00eda, Turismo y Agenda Digital ha desarrollado, a trav\u00e9s del IDEA, el <a href=\"http:\/\/www.idae.es\/ayudas-y-financiacion\/para-movilidad-y-vehiculos\/plan-movalt-vehiculos\">MOVALT<\/a>, un Plan de Apoyo a la Movilidad Alternativa, que tiene como objetivo fomentar la movilidad alternativa y eficiente, incentivando la adquisici\u00f3n de veh\u00edculos combustibles alternativos (GLP, gas natural, el\u00e9ctricos y pila de combustible) con 20 millones de euros, y de infraestructuras de recarga de veh\u00edculos el\u00e9ctricos, con 15 millones de euros adicionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Bolet\u00edn Oficial del Estado se ha determinado una <a href=\"https:\/\/www.boe.es\/diario_boe\/txt.php?id=BOE-A-2017-13158\">resoluci\u00f3n<\/a>, del Consejo de Administraci\u00f3n del EPE Instituto, para la diversificaci\u00f3n y el ahorro de la energ\u00eda (IDEAE), en la que se establecen las bases reguladoras de la convocatoria del programa de ayudas para la adquisici\u00f3n de veh\u00edculos de energ\u00edas alternativas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/plug-in-2783575_1280-768x1024.jpg\" alt=\"\" class=\"wp-image-11\" style=\"object-fit:cover\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">La implantaci\u00f3n del Plan MOVALT se realizar\u00e1 a trav\u00e9s de dos resoluciones:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>MOVALT \u2013 Veh\u00edculos, cuyas bases reguladoras se publicaron en el BOE de 14 de noviembre, y que se adjuntan en el presente correo, y<\/li>\n\n\n\n<li>MOVALT &#8211; Infraestructuras, de pr\u00f3xima publicaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s del Plan MOVALT \u2013 Infraestructuras se pretende incentivar con &nbsp;15 millones de euros la instalaci\u00f3n de infraestructuras de recarga de veh\u00edculos el\u00e9ctricos. Los beneficiarios podr\u00e1n ser administraciones, empresas p\u00fablicas y privadas. Se financiar\u00e1 la instalaci\u00f3n de infraestructuras de recarga tanto para uso p\u00fablico en el sector no residencial (aparcamientos p\u00fablicos, hoteles, centros comerciales, universidades, hospitales, pol\u00edgonos industriales, centros deportivos, etc.), como para uso privado en zonas de estacionamiento de empresas privadas, as\u00ed como para su ubicaci\u00f3n en la v\u00eda p\u00fablica y en la red de carreteras. La cuant\u00eda de las ayudas cubrir\u00e1 hasta el 60% del coste de inversi\u00f3n en el caso de entidades p\u00fablicas y PYMES, y el 40% para el resto de empresas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los veh\u00edculos propulsados con energ\u00edas alternativas a los combustibles f\u00f3siles convencionales est\u00e1n llamados a formar parte de la movilidad sostenible en el transporte a nivel global, tanto en las ciudades como en las carreteras, debido a sus beneficios en materia de diversificaci\u00f3n energ\u00e9tica y reducci\u00f3n de la dependencia de los productos petrol\u00edferos, as\u00ed como por la reducci\u00f3n de emisiones de CO2 y de otras emisiones contaminantes, ayudando por tanto a mejorar la calidad del aire de nuestras ciudades, como para disminuir la contaminaci\u00f3n ac\u00fastica y favorecer el consumo de energ\u00edas aut\u00f3ctonas, especialmente de fuentes renovables. Estas tecnolog\u00edas de transporte contin\u00faan representando, en el actual contexto econ\u00f3mico, un reto y una oportunidad para varios sectores estrat\u00e9gicos como son el energ\u00e9tico, el de automoci\u00f3n y el de tecnolog\u00edas de la informaci\u00f3n y las comunicaciones, tanto desde un punto de vista industrial y tecnol\u00f3gico, como energ\u00e9tico y medioambiental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fontaine:\u00a0<a href=\"http:\/\/www.afme.es\/es\/prensa\/noticias\/28-tecnicas\/538-el-minetad-aprueba-el-plan-movalt-con-el-que-se-incentivar%C3%A1-la-compra-de-veh%C3%ADculos-el%C3%A9ctricos-e-infraestructuras-de-recarga\">http:\/\/www.afme.es\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Energ\u00eda, Turismo y Agenda Digital ha desarrollado, a trav\u00e9s del IDEA, el MOVALT, un Plan de Apoyo a la Movilidad Alternativa, que tiene como objetivo fomentar la movilidad alternativa y eficiente, incentivando la adquisici\u00f3n de veh\u00edculos combustibles alternativos (GLP, gas natural, el\u00e9ctricos y pila de combustible) con 20 millones de euros, y&#8230;<\/p>","protected":false},"author":1,"featured_media":1738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[68],"tags":[],"class_list":["post-10","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coche-eletrico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan de Apoyo a la Movilidad Alternativa - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/plan-de-apoyo-a-la-movilidad-alternativa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan de Apoyo a la Movilidad Alternativa - Armengol\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Energ\u00eda, Turismo y Agenda Digital ha desarrollado, a trav\u00e9s del IDEA, el MOVALT, un Plan de Apoyo a la Movilidad Alternativa, que tiene como objetivo fomentar la movilidad alternativa y eficiente, incentivando la adquisici\u00f3n de veh\u00edculos combustibles alternativos (GLP, gas natural, el\u00e9ctricos y pila de combustible) con 20 millones de euros, y...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/plan-de-apoyo-a-la-movilidad-alternativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-30T12:51:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T12:10:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"Plan de Apoyo a la Movilidad Alternativa\",\"datePublished\":\"2017-11-30T12:51:38+00:00\",\"dateModified\":\"2024-01-24T12:10:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/\"},\"wordCount\":487,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/electric-car-2728131_1280.png\",\"articleSection\":[\"Coche el\u00e9trico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/\",\"name\":\"Plan de Apoyo a la Movilidad Alternativa - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/electric-car-2728131_1280.png\",\"datePublished\":\"2017-11-30T12:51:38+00:00\",\"dateModified\":\"2024-01-24T12:10:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/electric-car-2728131_1280.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/electric-car-2728131_1280.png\",\"width\":1280,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/plan-de-apoyo-a-la-movilidad-alternativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de Apoyo a la Movilidad Alternativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan de Apoyo a la Movilidad Alternativa - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/plan-de-apoyo-a-la-movilidad-alternativa\/","og_locale":"fr_FR","og_type":"article","og_title":"Plan de Apoyo a la Movilidad Alternativa - Armengol","og_description":"El Ministerio de Energ\u00eda, Turismo y Agenda Digital ha desarrollado, a trav\u00e9s del IDEA, el MOVALT, un Plan de Apoyo a la Movilidad Alternativa, que tiene como objetivo fomentar la movilidad alternativa y eficiente, incentivando la adquisici\u00f3n de veh\u00edculos combustibles alternativos (GLP, gas natural, el\u00e9ctricos y pila de combustible) con 20 millones de euros, y...","og_url":"https:\/\/napoleon-armengol.com\/fr\/plan-de-apoyo-a-la-movilidad-alternativa\/","og_site_name":"Armengol","article_published_time":"2017-11-30T12:51:38+00:00","article_modified_time":"2024-01-24T12:10:36+00:00","og_image":[{"width":1280,"height":512,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"Plan de Apoyo a la Movilidad Alternativa","datePublished":"2017-11-30T12:51:38+00:00","dateModified":"2024-01-24T12:10:36+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/"},"wordCount":487,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280.png","articleSection":["Coche el\u00e9trico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/","url":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/","name":"Plan de Apoyo a la Movilidad Alternativa - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280.png","datePublished":"2017-11-30T12:51:38+00:00","dateModified":"2024-01-24T12:10:36+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280.png","width":1280,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/plan-de-apoyo-a-la-movilidad-alternativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Plan de Apoyo a la Movilidad Alternativa"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":68,"label":"Coche el\u00e9trico"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2017\/11\/electric-car-2728131_1280-1024x410.png",1024,410,true],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":68,"name":"Coche el\u00e9trico","slug":"coche-eletrico","term_group":0,"term_taxonomy_id":68,"taxonomy":"category","description":"","parent":0,"count":63,"filter":"raw","term_order":"0","cat_ID":68,"category_count":63,"category_description":"","cat_name":"Coche el\u00e9trico","category_nicename":"coche-eletrico","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":6,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/10\/revisions"}],"predecessor-version":[{"id":2410,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/10\/revisions\/2410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/1738"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=10"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=10"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}