{"id":116,"date":"2018-08-01T13:13:39","date_gmt":"2018-08-01T13:13:39","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=116"},"modified":"2024-03-04T10:34:43","modified_gmt":"2024-03-04T09:34:43","slug":"bateria-conceptos-tecnicos-de-los-coches-electricos","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/bateria-conceptos-tecnicos-de-los-coches-electricos\/","title":{"rendered":"Batterie : concepts techniques des voitures \u00e9lectriques"},"content":{"rendered":"<p align=\"justify\">Aunque no lo creamos, los coches el\u00e9ctricos hace mucho tiempo que existen, es m\u00e1s, en la primera d\u00e9cada del siglo XX, este tipo de coches representaban un tercio del parque m\u00f3vil. Tras dejarlo de lado casi un siglo, actualmente los coches el\u00e9ctricos vuelen a ser una alternativa a los coches de combusti\u00f3n interna. Gracias a las bater\u00edas con mayor capacidad y a los grandes avances tecnol\u00f3gicos, actualmente podemos ver coches el\u00e9ctricos por el centro de cualquier ciudad.<\/p>\n<p align=\"justify\">Sin embargo, despu\u00e9s de tanto tiempo utilizando \u00fanicamente coches di\u00e9sel y de gasolina, ya no sabemos cu\u00e1les son los conceptos y factores que hacen que un coche el\u00e9ctrico sea mejor o peor que otro. De esta forma, en el art\u00edculo de hoy hablaremos sobre algunos conceptos b\u00e1sicos que debemos conocer si queremos poder hablar de coches el\u00e9ctricos con personas entendidas.<\/p>\n<h2>La bater\u00eda de los coches el\u00e9ctricos<\/h2>\n<p align=\"justify\">La bater\u00eda el\u00e9ctrica la debemos entender como un almac\u00e9n en el que se guarda toda la energ\u00eda qu\u00edmica. Dentro de la bater\u00eda pueden hacer una o m\u00e1s celdas electroqu\u00edmicas que convierten esta energ\u00eda qu\u00edmica en corriente el\u00e9ctrica. Aunque existen distintos tipos, la bater\u00eda m\u00e1s utilizada actualmente en el sector del autom\u00f3vil son las bater\u00edas de iones de litio.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-117 aligncenter\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/carga-del-coche-electrico-de-la-fuente-de-alimentacion_53089-80.jpg\" alt=\"\" width=\"685\" height=\"456\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/carga-del-coche-electrico-de-la-fuente-de-alimentacion_53089-80.jpg 626w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/carga-del-coche-electrico-de-la-fuente-de-alimentacion_53089-80-300x200.jpg 300w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/p>\n<p align=\"justify\">La capacidad de una beter\u00eda se medir\u00e1 seg\u00fan la carga que puede almacenarse en ella, esta capacidad se puede medie en amperios-hora (Ah). De esta forma, si una bater\u00eda tiene una capacidad de carga de 1 amperio-hora significa que puede suministrar una intensidad de corriente de 1 amperio durante 1 hora.<\/p>\n<p align=\"justify\">La densidad de una bater\u00eda es la relaci\u00f3n de la masa por unidad de volumen de electrolito. Para que lo entendamos mejor, una gran densidad de energ\u00eda permitir\u00e1 acumular mucha m\u00e1s carga por unidad de peso y volumen. De esta forma, cuanto mayor es la densidad de la bater\u00eda, menor peso y tama\u00f1o podr\u00e1 tener la bater\u00eda.<\/p>\n<p align=\"justify\">Por otro lado, el kWh se entiende como la capacidad de energ\u00eda que puede transferir una bater\u00eda, tanto puede ser suministr\u00e1ndola al motor como recibi\u00e9ndola de un cargador. De esta forma, debemos entender que la cantidad de energ\u00eda que una bater\u00eda es capaz de suministrar depende directamente de su capacidad y voltaje.<\/p>\n<p align=\"justify\">La medida kWh tambi\u00e9n sirve para expresar la capacidad de carga en relaci\u00f3n a la velocidad en la que la bater\u00eda se carga. Como ejemplo, si una bater\u00eda dispone de 90 kWh se necesitar\u00e1n 75 minutos para recargar la bater\u00eda desde 0% hasta 100%.<\/p>\n<p align=\"justify\">Finalmente, cabe destacar que los kWh sirven para expresar el consumo, la capacidad y tiempo m\u00e1ximo a la que la bater\u00eda se puede cambiar de un modelo de coche el\u00e9ctrico. Siempre teniendo en cuenta que el tiempo de carga puede variar en funci\u00f3n del amperaje y voltaje del suministro.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aunque no lo creamos, los coches el\u00e9ctricos hace mucho tiempo que existen, es m\u00e1s, en la primera d\u00e9cada del siglo XX, este tipo de coches representaban un tercio del parque m\u00f3vil. Tras dejarlo de lado casi un siglo, actualmente los coches el\u00e9ctricos vuelen a ser una alternativa a los coches de combusti\u00f3n interna. Gracias a&#8230;<\/p>","protected":false},"author":1,"featured_media":118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[68],"tags":[96,95,97,106,98,146,149,135,110,100,111,114],"class_list":["post-116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coche-eletrico","tag-ahorro-energetico","tag-coche-electrico","tag-coches-electricos","tag-contaminacion","tag-eficiencia-energetica","tag-energia","tag-energias-renovables","tag-inversion","tag-medio-ambiente","tag-movilidad-electrica","tag-movilidad-sostenible","tag-vehiculos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/bateria-conceptos-tecnicos-de-los-coches-electricos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos - Armengol\" \/>\n<meta property=\"og:description\" content=\"Aunque no lo creamos, los coches el\u00e9ctricos hace mucho tiempo que existen, es m\u00e1s, en la primera d\u00e9cada del siglo XX, este tipo de coches representaban un tercio del parque m\u00f3vil. Tras dejarlo de lado casi un siglo, actualmente los coches el\u00e9ctricos vuelen a ser una alternativa a los coches de combusti\u00f3n interna. Gracias a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/bateria-conceptos-tecnicos-de-los-coches-electricos\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-01T13:13:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-04T09:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos\",\"datePublished\":\"2018-08-01T13:13:39+00:00\",\"dateModified\":\"2024-03-04T09:34:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/\"},\"wordCount\":516,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg\",\"keywords\":[\"ahorro energ\u00e9tico\",\"Coche el\u00e9ctrico\",\"coches el\u00e9ctricos\",\"contaminaci\u00f3n\",\"eficiencia energ\u00e9tica\",\"energ\u00eda\",\"energ\u00edas renovables\",\"inversi\u00f3n\",\"medio ambiente\",\"movilidad el\u00e9ctrica\",\"movilidad sostenible\",\"veh\u00edculos\"],\"articleSection\":[\"Coche el\u00e9trico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/\",\"name\":\"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg\",\"datePublished\":\"2018-08-01T13:13:39+00:00\",\"dateModified\":\"2024-03-04T09:34:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg\",\"width\":626,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/bateria-conceptos-tecnicos-de-los-coches-electricos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/bateria-conceptos-tecnicos-de-los-coches-electricos\/","og_locale":"fr_FR","og_type":"article","og_title":"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos - Armengol","og_description":"Aunque no lo creamos, los coches el\u00e9ctricos hace mucho tiempo que existen, es m\u00e1s, en la primera d\u00e9cada del siglo XX, este tipo de coches representaban un tercio del parque m\u00f3vil. Tras dejarlo de lado casi un siglo, actualmente los coches el\u00e9ctricos vuelen a ser una alternativa a los coches de combusti\u00f3n interna. Gracias a...","og_url":"https:\/\/napoleon-armengol.com\/fr\/bateria-conceptos-tecnicos-de-los-coches-electricos\/","og_site_name":"Armengol","article_published_time":"2018-08-01T13:13:39+00:00","article_modified_time":"2024-03-04T09:34:43+00:00","og_image":[{"width":626,"height":417,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos","datePublished":"2018-08-01T13:13:39+00:00","dateModified":"2024-03-04T09:34:43+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/"},"wordCount":516,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg","keywords":["ahorro energ\u00e9tico","Coche el\u00e9ctrico","coches el\u00e9ctricos","contaminaci\u00f3n","eficiencia energ\u00e9tica","energ\u00eda","energ\u00edas renovables","inversi\u00f3n","medio ambiente","movilidad el\u00e9ctrica","movilidad sostenible","veh\u00edculos"],"articleSection":["Coche el\u00e9trico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/","url":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/","name":"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg","datePublished":"2018-08-01T13:13:39+00:00","dateModified":"2024-03-04T09:34:43+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg","width":626,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/bateria-conceptos-tecnicos-de-los-coches-electricos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Bater\u00eda: conceptos t\u00e9cnicos de los coches el\u00e9ctricos"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":68,"label":"Coche el\u00e9trico"}],"post_tag":[{"value":96,"label":"ahorro energ\u00e9tico"},{"value":95,"label":"Coche el\u00e9ctrico"},{"value":97,"label":"coches el\u00e9ctricos"},{"value":106,"label":"contaminaci\u00f3n"},{"value":98,"label":"eficiencia energ\u00e9tica"},{"value":146,"label":"energ\u00eda"},{"value":149,"label":"energ\u00edas renovables"},{"value":135,"label":"inversi\u00f3n"},{"value":110,"label":"medio ambiente"},{"value":100,"label":"movilidad el\u00e9ctrica"},{"value":111,"label":"movilidad sostenible"},{"value":114,"label":"veh\u00edculos"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2018\/08\/mecanico-que-sostiene-un-tablero-de-la-orden-de-servicio-que-trabaja-en-garaje-servicio-de-reparacion_18497-346.jpg",626,417,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":68,"name":"Coche el\u00e9trico","slug":"coche-eletrico","term_group":0,"term_taxonomy_id":68,"taxonomy":"category","description":"","parent":0,"count":63,"filter":"raw","term_order":"0","cat_ID":68,"category_count":63,"category_description":"","cat_name":"Coche el\u00e9trico","category_nicename":"coche-eletrico","category_parent":0}],"tag_info":[{"term_id":96,"name":"ahorro energ\u00e9tico","slug":"ahorro-energetico","term_group":0,"term_taxonomy_id":96,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":95,"name":"Coche el\u00e9ctrico","slug":"coche-electrico","term_group":0,"term_taxonomy_id":95,"taxonomy":"post_tag","description":"","parent":0,"count":45,"filter":"raw","term_order":"0"},{"term_id":97,"name":"coches el\u00e9ctricos","slug":"coches-electricos","term_group":0,"term_taxonomy_id":97,"taxonomy":"post_tag","description":"","parent":0,"count":25,"filter":"raw","term_order":"0"},{"term_id":106,"name":"contaminaci\u00f3n","slug":"contaminacion","term_group":0,"term_taxonomy_id":106,"taxonomy":"post_tag","description":"","parent":0,"count":19,"filter":"raw","term_order":"0"},{"term_id":98,"name":"eficiencia energ\u00e9tica","slug":"eficiencia-energetica","term_group":0,"term_taxonomy_id":98,"taxonomy":"post_tag","description":"","parent":0,"count":36,"filter":"raw","term_order":"0"},{"term_id":146,"name":"energ\u00eda","slug":"energia","term_group":0,"term_taxonomy_id":146,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw","term_order":"0"},{"term_id":149,"name":"energ\u00edas renovables","slug":"energias-renovables","term_group":0,"term_taxonomy_id":149,"taxonomy":"post_tag","description":"","parent":0,"count":30,"filter":"raw","term_order":"0"},{"term_id":135,"name":"inversi\u00f3n","slug":"inversion","term_group":0,"term_taxonomy_id":135,"taxonomy":"post_tag","description":"","parent":0,"count":31,"filter":"raw","term_order":"0"},{"term_id":110,"name":"medio ambiente","slug":"medio-ambiente","term_group":0,"term_taxonomy_id":110,"taxonomy":"post_tag","description":"","parent":0,"count":29,"filter":"raw","term_order":"0"},{"term_id":100,"name":"movilidad el\u00e9ctrica","slug":"movilidad-electrica","term_group":0,"term_taxonomy_id":100,"taxonomy":"post_tag","description":"","parent":0,"count":41,"filter":"raw","term_order":"0"},{"term_id":111,"name":"movilidad sostenible","slug":"movilidad-sostenible","term_group":0,"term_taxonomy_id":111,"taxonomy":"post_tag","description":"","parent":0,"count":31,"filter":"raw","term_order":"0"},{"term_id":114,"name":"veh\u00edculos","slug":"vehiculos","term_group":0,"term_taxonomy_id":114,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/116\/revisions"}],"predecessor-version":[{"id":2373,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/116\/revisions\/2373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/118"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}