{"id":1980,"date":"2019-04-29T09:10:47","date_gmt":"2019-04-29T09:10:47","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=403"},"modified":"2024-01-24T12:24:53","modified_gmt":"2024-01-24T11:24:53","slug":"es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/","title":{"rendered":"Est-il possible de recharger la voiture \u00e9lectrique en seulement six minutes ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En Espa\u00f1a ya existe un lugar para\npoder llevar a cabo la recarga ultrarr\u00e1pida en coches el\u00e9ctricos, que se\nefect\u00faa en solo seis minutos. La marca de la estaci\u00f3n de servicio es Repsol, una\nmarca muy comprometida con la sostenibilidad. Repsol apuesta por la movilidad\neficiente, no s\u00f3lo por la instalaci\u00f3n de este punto de recarga ultrarr\u00e1pida,\nsino que tambi\u00e9n cuenta con una parte de Wibe, una empresa de carsharing y de\nScutum, que suministra a empresas de motosharing. Tal como indican en su web,\ndesde Repsol impulsan y aplican planes de sostenibilidad para reducir la\nintensidad energ\u00e9tica de carbono y apuestan por la eficiencia energ\u00e9tica, para\nreducir las emisiones de gases de efecto invernadero (GEI).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El primer punto de recarga ultrarr\u00e1pida en Espa\u00f1a para coches\nel\u00e9ctricos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de la primera\nelectrolinera de carga ultrar\u00e1pida en Espa\u00f1a que est\u00e1 en funcionamiento y est\u00e1\nubicada en el t\u00e9rmino alav\u00e9s de Lopidana, cerca de Vitoria. Es el \u00fanico punto de\nrecarga ultrarr\u00e1pida en toda Espa\u00f1a que permite cargar un coche el\u00e9ctrico en\ntan solo seis minutos, el mismo tiempo que tarda un veh\u00edculo convencional en\nrepostar.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-5.jpg\" alt=\"\" class=\"wp-image-406\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una nueva instalaci\u00f3n que ha sido\nimpulsada por Repsol y el Ente Vasco de la Energ\u00eda (EVE), que cuenta ya con\ncuatro postes que soportan una potencia m\u00e1xima de 700 kilovatios. Es apta para\nque los veh\u00edculos puedan recorrer entre 150 y 200 kil\u00f3metros de distancia y est\u00e1\npreparado para dar servicio a cualquier tipo de veh\u00edculo el\u00e9ctrico del mercado,\nporque dispone de conectores est\u00e1ndar de recarga Combo CCS y CHadeMO. La\ninstalaci\u00f3n est\u00e1 dise\u00f1ada para poder enchufar 350 kilovatios a dos veh\u00edculos al\nmismo tiempo o recargar cuatro turismos con 175 kilovatios cada uno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El coste de cada carga completa\nes de ocho euros y cuenta con una potencia m\u00e1xima de 700 kilovatios, que puede\nrepartirla entre sus cuatro puntos de suministro dependiendo de la capacidad de\ncarga de los veh\u00edculos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una electrolinera singular situada en un punto estrat\u00e9gico<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La electrolinera est\u00e1 situada en\nun lugar privilegiado de la carretera N-I, a 130 kil\u00f3metros de la frontera con\nFrancia y a 330 km de Madrid, lo que permite a los coches el\u00e9ctricos hacer\ntrayectos entre Madrid y Francia con una sola recarga. Esto quiere decir que\nestamos hablando de un gran avance para favorecer el uso del veh\u00edculo\nel\u00e9ctrico, como medio de transporte interurbano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A este punto de recarga\nultrarr\u00e1pida le seguir\u00e1n cuatro instalaciones muy parecidas que ir\u00e1n ubicadas\nen los ejes de la A-1 (Madrid-Ir\u00fan) y en la A-2 (Madrid-La Junquera), que\ncontempla el despliegue de una gran red piloto de 14 instalaciones semejantes, en\ncorredores europeos de transporte de Espa\u00f1a, Francia e Italia.<\/p>","protected":false},"excerpt":{"rendered":"<p>En Espa\u00f1a ya existe un lugar para poder llevar a cabo la recarga ultrarr\u00e1pida en coches el\u00e9ctricos, que se efect\u00faa en solo seis minutos. La marca de la estaci\u00f3n de servicio es Repsol, una marca muy comprometida con la sostenibilidad. Repsol apuesta por la movilidad eficiente, no s\u00f3lo por la instalaci\u00f3n de este punto de&#8230;<\/p>","protected":false},"author":1,"featured_media":1779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[68],"tags":[95,350,351,352,353,354,355,356],"class_list":["post-1980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coche-eletrico","tag-coche-electrico","tag-coche-electrico-en-espana","tag-punto-de-recarga","tag-punto-de-recarga-coche-electrico","tag-punto-de-recarga-ultrarrapida","tag-recarga-ultrarrapida","tag-repsol","tag-vitoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos? - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos? - Armengol\" \/>\n<meta property=\"og:description\" content=\"En Espa\u00f1a ya existe un lugar para poder llevar a cabo la recarga ultrarr\u00e1pida en coches el\u00e9ctricos, que se efect\u00faa en solo seis minutos. La marca de la estaci\u00f3n de servicio es Repsol, una marca muy comprometida con la sostenibilidad. Repsol apuesta por la movilidad eficiente, no s\u00f3lo por la instalaci\u00f3n de este punto de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T09:10:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T11:24:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos?\",\"datePublished\":\"2019-04-29T09:10:47+00:00\",\"dateModified\":\"2024-01-24T11:24:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/coche-electrico-4.jpg\",\"keywords\":[\"Coche el\u00e9ctrico\",\"coche el\u00e9ctrico en Espa\u00f1a\",\"punto de recarga\",\"punto de recarga coche el\u00e9ctrico\",\"punto de recarga ultrarr\u00e1pida\",\"recarga ultrarr\u00e1pida\",\"Repsol\",\"Vitoria\"],\"articleSection\":[\"Coche el\u00e9trico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/\",\"name\":\"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos? - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/coche-electrico-4.jpg\",\"datePublished\":\"2019-04-29T09:10:47+00:00\",\"dateModified\":\"2024-01-24T11:24:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/coche-electrico-4.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/coche-electrico-4.jpg\",\"width\":626,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos? - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos? - Armengol","og_description":"En Espa\u00f1a ya existe un lugar para poder llevar a cabo la recarga ultrarr\u00e1pida en coches el\u00e9ctricos, que se efect\u00faa en solo seis minutos. La marca de la estaci\u00f3n de servicio es Repsol, una marca muy comprometida con la sostenibilidad. Repsol apuesta por la movilidad eficiente, no s\u00f3lo por la instalaci\u00f3n de este punto de...","og_url":"https:\/\/napoleon-armengol.com\/fr\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/","og_site_name":"Armengol","article_published_time":"2019-04-29T09:10:47+00:00","article_modified_time":"2024-01-24T11:24:53+00:00","og_image":[{"width":626,"height":417,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos?","datePublished":"2019-04-29T09:10:47+00:00","dateModified":"2024-01-24T11:24:53+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/"},"wordCount":490,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg","keywords":["Coche el\u00e9ctrico","coche el\u00e9ctrico en Espa\u00f1a","punto de recarga","punto de recarga coche el\u00e9ctrico","punto de recarga ultrarr\u00e1pida","recarga ultrarr\u00e1pida","Repsol","Vitoria"],"articleSection":["Coche el\u00e9trico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/","url":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/","name":"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos? - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg","datePublished":"2019-04-29T09:10:47+00:00","dateModified":"2024-01-24T11:24:53+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg","width":626,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/es-posible-cargar-el-coche-electrico-en-tan-solo-seis-minutos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfEs posible cargar el coche el\u00e9ctrico en tan s\u00f3lo seis minutos?"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":68,"label":"Coche el\u00e9trico"}],"post_tag":[{"value":95,"label":"Coche el\u00e9ctrico"},{"value":350,"label":"coche el\u00e9ctrico en Espa\u00f1a"},{"value":351,"label":"punto de recarga"},{"value":352,"label":"punto de recarga coche el\u00e9ctrico"},{"value":353,"label":"punto de recarga ultrarr\u00e1pida"},{"value":354,"label":"recarga ultrarr\u00e1pida"},{"value":355,"label":"Repsol"},{"value":356,"label":"Vitoria"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2019\/04\/coche-electrico-4.jpg",626,417,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":68,"name":"Coche el\u00e9trico","slug":"coche-eletrico","term_group":0,"term_taxonomy_id":68,"taxonomy":"category","description":"","parent":0,"count":63,"filter":"raw","term_order":"0","cat_ID":68,"category_count":63,"category_description":"","cat_name":"Coche el\u00e9trico","category_nicename":"coche-eletrico","category_parent":0}],"tag_info":[{"term_id":95,"name":"Coche el\u00e9ctrico","slug":"coche-electrico","term_group":0,"term_taxonomy_id":95,"taxonomy":"post_tag","description":"","parent":0,"count":45,"filter":"raw","term_order":"0"},{"term_id":350,"name":"coche el\u00e9ctrico en Espa\u00f1a","slug":"coche-electrico-en-espana","term_group":0,"term_taxonomy_id":350,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":351,"name":"punto de recarga","slug":"punto-de-recarga","term_group":0,"term_taxonomy_id":351,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","term_order":"0"},{"term_id":352,"name":"punto de recarga coche el\u00e9ctrico","slug":"punto-de-recarga-coche-electrico","term_group":0,"term_taxonomy_id":352,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":353,"name":"punto de recarga ultrarr\u00e1pida","slug":"punto-de-recarga-ultrarrapida","term_group":0,"term_taxonomy_id":353,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":354,"name":"recarga ultrarr\u00e1pida","slug":"recarga-ultrarrapida","term_group":0,"term_taxonomy_id":354,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":355,"name":"Repsol","slug":"repsol","term_group":0,"term_taxonomy_id":355,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":356,"name":"Vitoria","slug":"vitoria","term_group":0,"term_taxonomy_id":356,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/1980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=1980"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/1980\/revisions"}],"predecessor-version":[{"id":2325,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/1980\/revisions\/2325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/1779"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=1980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=1980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=1980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}