{"id":1995,"date":"2020-02-07T12:58:33","date_gmt":"2020-02-07T12:58:33","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=585"},"modified":"2024-01-24T12:22:03","modified_gmt":"2024-01-24T11:22:03","slug":"sabes-que-es-el-acero-galvanizado","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/sabes-que-es-el-acero-galvanizado\/","title":{"rendered":"Savez-vous ce qu&#039;est l&#039;acier galvanis\u00e9 ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En tant que sp\u00e9cialistes du <strong>tuyau galvanis\u00e9<\/strong>, aujourd&#039;hui nous voulons vous parler de l&#039;acier galvanis\u00e9, pour que vous sachiez ce que c&#039;est et \u00e0 quoi il sert. C&#039;est un type d&#039;acier trait\u00e9 avec un traitement dans lequel il est recouvert de diff\u00e9rentes couches de zinc. Ces couches prot\u00e8gent l\u2019acier et l\u2019emp\u00eachent de rouiller. L&#039;acier galvanis\u00e9 est un mat\u00e9riau dot\u00e9 d&#039;une finition tr\u00e8s durable et r\u00e9sistante aux rayures, ce qui le rend plus attractif pour de nombreux consommateurs et est utilis\u00e9 pour la fabrication de nombreux composants \u00e0 usage industriel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment est-ce fait ?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les diff\u00e9rentes pi\u00e8ces en acier sont d&#039;abord fa\u00e7onn\u00e9es selon la forme souhait\u00e9e, par exemple des cl\u00e9s, des clous, des anneaux, des t\u00f4les, des fils ou des tubes. Ensuite, une technique de galvanisation est appliqu\u00e9e, telle que la galvanisation par immersion, une m\u00e9thode courante qui consiste \u00e0 immerger l&#039;acier dans du zinc en fusion, de sorte qu&#039;il se produise une r\u00e9action chimique dans laquelle des liaisons permanentes sont g\u00e9n\u00e9r\u00e9es entre les deux \u00e9l\u00e9ments et, lorsqu&#039;il refroidit, il reste trois couches diff\u00e9rentes. , la couche ext\u00e9rieure est uniquement en zinc, la couche int\u00e9rieure est en acier et en zinc et la couche la plus int\u00e9rieure est en acier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que l&#039;on puisse trouver d&#039;autres syst\u00e8mes pour fabriquer de l&#039;acier galvanis\u00e9 comme la galvanisation continue, une technique qui fait passer de fines feuilles ou des fils d&#039;acier \u00e0 travers du zinc fondu. Et on ne peut cesser de parler d\u2019\u00e9lectrozingage ou de galvanisation par immersion, qui est consid\u00e9r\u00e9e comme l\u2019une des techniques les plus r\u00e9sistantes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-2.jpg\" alt=\"\" class=\"wp-image-587\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tuyau galvanis\u00e9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>tuyau galvanis\u00e9<\/strong> Il s&#039;agit d&#039;un \u00e9l\u00e9ment fabriqu\u00e9 en acier et recouvert de zinc, afin qu&#039;il soit plus r\u00e9sistant \u00e0 la corrosion et ne rouille pas, en plus d&#039;apporter une embellissement esth\u00e9tique \u00e0 la pi\u00e8ce. Il se caract\u00e9rise par sa solidit\u00e9, sa durabilit\u00e9, sa fermet\u00e9, sa capacit\u00e9 \u00e0 r\u00e9sister aux changements extr\u00eames de temp\u00e9rature, sa r\u00e9sistance \u00e0 la pression et aux \u00e9l\u00e9ments destructeurs, etc. Cela leur permet d&#039;\u00eatre un \u00e9l\u00e9ment tr\u00e8s utile dans n&#039;importe quelle industrie, puisque leur forme peut \u00eatre adapt\u00e9e en fonction de l&#039;usage qui va en \u00eatre fait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>tuyau galvanis\u00e9<\/strong> Il peut \u00eatre utilis\u00e9 pour l&#039;environnement domestique, afin de r\u00e9aliser des canalisations dans lesquelles circule du gaz, de l&#039;eau et tout autre mat\u00e9riau ou pour les industries, car il poss\u00e8de des caract\u00e9ristiques parfaites pour s&#039;adapter aux besoins de ce secteur. Il peut \u00e9galement \u00eatre utilis\u00e9 pour d&#039;autres applications, comme par exemple pour l&#039;installation de cl\u00f4tures, de supports de cl\u00f4ture, de serres, de portails ou de cages.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez Armengol nous sommes sp\u00e9cialistes dans la fabrication, l&#039;installation et la distribution de <strong>tuyau galvanis\u00e9<\/strong> et nous pouvons vous expliquer qu&#039;il existe trois m\u00e9thodes pour le fabriquer ; Acier \u00e9tir\u00e9 ou sans soudure (la forme la plus courante), avec un joint longitudinal (c&#039;est la partie la plus faible du tuyau et marque la tension maximale admissible) et avec soudage h\u00e9lico\u00efdal (on r\u00e9alise une soudure qui n&#039;est pas droite, mais qui longe le tuyau et le suit comme s&#039;il s&#039;agissait d&#039;un fil.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrez sur notre site Internet pour d\u00e9couvrir tous les avantages de <strong>tuyau galvanis\u00e9<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Como especialistas en el tubo galvanizado, hoy queremos hablarte del acero galvanizado, para que sepas qu\u00e9 es y qu\u00e9 usos tiene. Es un tipo de acero procesado con un tratamiento en el cual queda recubierto de diversas capas de zinc. Estas capas se ocupan de proteger al acero y evitan que se oxide. El acero&#8230;<\/p>","protected":false},"author":1,"featured_media":1814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[119],"tags":[428,251,252,255],"class_list":["post-1995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnico","tag-acero","tag-tubo","tag-tubo-galvanizado","tag-zinc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfSabes qu\u00e9 es el acero galvanizado? - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/sabes-que-es-el-acero-galvanizado\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSabes qu\u00e9 es el acero galvanizado? - Armengol\" \/>\n<meta property=\"og:description\" content=\"Como especialistas en el tubo galvanizado, hoy queremos hablarte del acero galvanizado, para que sepas qu\u00e9 es y qu\u00e9 usos tiene. Es un tipo de acero procesado con un tratamiento en el cual queda recubierto de diversas capas de zinc. Estas capas se ocupan de proteger al acero y evitan que se oxide. El acero...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/sabes-que-es-el-acero-galvanizado\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-07T12:58:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T11:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfSabes qu\u00e9 es el acero galvanizado?\",\"datePublished\":\"2020-02-07T12:58:33+00:00\",\"dateModified\":\"2024-01-24T11:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tubo-galvanizado-1.jpg\",\"keywords\":[\"acero\",\"tubo\",\"tubo galvanizado\",\"zinc\"],\"articleSection\":[\"T\u00e9cnico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/\",\"name\":\"\u00bfSabes qu\u00e9 es el acero galvanizado? - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tubo-galvanizado-1.jpg\",\"datePublished\":\"2020-02-07T12:58:33+00:00\",\"dateModified\":\"2024-01-24T11:22:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tubo-galvanizado-1.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/tubo-galvanizado-1.jpg\",\"width\":626,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/sabes-que-es-el-acero-galvanizado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSabes qu\u00e9 es el acero galvanizado?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSabes qu\u00e9 es el acero galvanizado? - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/sabes-que-es-el-acero-galvanizado\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfSabes qu\u00e9 es el acero galvanizado? - Armengol","og_description":"Como especialistas en el tubo galvanizado, hoy queremos hablarte del acero galvanizado, para que sepas qu\u00e9 es y qu\u00e9 usos tiene. Es un tipo de acero procesado con un tratamiento en el cual queda recubierto de diversas capas de zinc. Estas capas se ocupan de proteger al acero y evitan que se oxide. El acero...","og_url":"https:\/\/napoleon-armengol.com\/fr\/sabes-que-es-el-acero-galvanizado\/","og_site_name":"Armengol","article_published_time":"2020-02-07T12:58:33+00:00","article_modified_time":"2024-01-24T11:22:03+00:00","og_image":[{"width":626,"height":417,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfSabes qu\u00e9 es el acero galvanizado?","datePublished":"2020-02-07T12:58:33+00:00","dateModified":"2024-01-24T11:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/"},"wordCount":525,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg","keywords":["acero","tubo","tubo galvanizado","zinc"],"articleSection":["T\u00e9cnico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/","url":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/","name":"\u00bfSabes qu\u00e9 es el acero galvanizado? - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg","datePublished":"2020-02-07T12:58:33+00:00","dateModified":"2024-01-24T11:22:03+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg","width":626,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/sabes-que-es-el-acero-galvanizado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfSabes qu\u00e9 es el acero galvanizado?"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":119,"label":"T\u00e9cnico"}],"post_tag":[{"value":428,"label":"acero"},{"value":251,"label":"tubo"},{"value":252,"label":"tubo galvanizado"},{"value":255,"label":"zinc"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/02\/tubo-galvanizado-1.jpg",626,417,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":119,"name":"T\u00e9cnico","slug":"tecnico","term_group":0,"term_taxonomy_id":119,"taxonomy":"category","description":"","parent":0,"count":30,"filter":"raw","term_order":"0","cat_ID":119,"category_count":30,"category_description":"","cat_name":"T\u00e9cnico","category_nicename":"tecnico","category_parent":0}],"tag_info":[{"term_id":428,"name":"acero","slug":"acero","term_group":0,"term_taxonomy_id":428,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":251,"name":"tubo","slug":"tubo","term_group":0,"term_taxonomy_id":251,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":252,"name":"tubo galvanizado","slug":"tubo-galvanizado","term_group":0,"term_taxonomy_id":252,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw","term_order":"0"},{"term_id":255,"name":"zinc","slug":"zinc","term_group":0,"term_taxonomy_id":255,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/1995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=1995"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/1995\/revisions"}],"predecessor-version":[{"id":2287,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/1995\/revisions\/2287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/1814"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=1995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=1995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=1995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}