{"id":2012,"date":"2020-07-28T07:59:38","date_gmt":"2020-07-28T07:59:38","guid":{"rendered":"http:\/\/blog-napoleon-armengol.com\/?p=667"},"modified":"2024-01-24T12:20:44","modified_gmt":"2024-01-24T11:20:44","slug":"cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/","title":{"rendered":"Quelle est la voiture \u00e9lectrique qui bat des records de ventes en Europe ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.renault.es\/electricos\/zoe.html\">Renault Zo\u00e9<\/a> Il a clairement \u00e9t\u00e9 le v\u00e9hicule \u00e9lectrique le plus vendu en Europe au cours du premier semestre 2020, d\u00e9passant des mod\u00e8les tr\u00e8s cot\u00e9s comme la Tesla Model 3 ou la Volkswagen e-Golf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son prix est de 30 000 euros et il a une autonomie de pr\u00e8s de 400 km, se positionnant comme l&#039;un des mod\u00e8les de r\u00e9f\u00e9rence au niveau europ\u00e9en et conqu\u00e9rant les consommateurs d\u00e8s le premier instant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La marque fran\u00e7aise a commenc\u00e9 \u00e0 commercialiser le mod\u00e8le Renault Zoe en 2013 et depuis lors, elle bat des records de ventes ann\u00e9e apr\u00e8s ann\u00e9e, vendant 37 540 unit\u00e9s au cours du premier semestre 2020, r\u00e9alisant une croissance des ventes pour le 50%, avec un record de ventes mensuel au cours du mois de 2020. Juin, avec 11 000 v\u00e9hicules \u00e9lectriques de ce mod\u00e8le.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 ses d\u00e9buts, elle ne semblait pas \u00eatre un mod\u00e8le aussi comp\u00e9titif et ne se distinguait pas des autres mod\u00e8les, mais apr\u00e8s avoir am\u00e9lior\u00e9 son efficacit\u00e9 en termes d&#039;autonomie, de puissance et de design, la Renault Zoe a conquis les consommateurs dans toute l&#039;Europe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Leader incontest\u00e9 des v\u00e9hicules \u00e9lectriques au niveau europ\u00e9en<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir \u00e9merg\u00e9 en 2019 et avoir \u00e9t\u00e9 leader des ventes cette ann\u00e9e, la Renault Zo\u00e9 est devenue le leader incontest\u00e9 du march\u00e9 du v\u00e9hicule \u00e9lectrique au niveau europ\u00e9en. Au cours du premier semestre de cette ann\u00e9e, ils ont vendu plus de voitures que pendant toute l&#039;ann\u00e9e 2017, leur acceptation sur le march\u00e9 est donc plus que positive. Il faut tenir compte du fait que le gouvernement fran\u00e7ais propose une aide aux consommateurs pour favoriser l&#039;achat de v\u00e9hicules \u00e9lectriques, en accordant jusqu&#039;\u00e0 7 000 euros pour l&#039;achat d&#039;une voiture \u00e9lectrique, sachant qu&#039;en Allemagne ils offrent une aide de 9 000 et en Espagne jusqu&#039;\u00e0 4 000 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#039;est un v\u00e9hicule urbain tr\u00e8s polyvalent en mati\u00e8re de recharge et il peut \u00eatre recharg\u00e9 sur tous types de bornes de recharge, Wallbox, borne de recharge rapide, borne de recharge publique, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour assurer la s\u00e9curit\u00e9 au volant, la Renault Zo\u00e9 dispose d&#039;une multitude de syst\u00e8mes d&#039;aide \u00e0 la conduite qui garantissent une conduite s\u00fbre et facilitent les man\u0153uvres. C&#039;est une voiture qui peut transporter jusqu&#039;\u00e0 cinq occupants r\u00e9els et parmi les mises \u00e0 jour que ce mod\u00e8le a acquises, les inserts textiles dans les moulures ont fait gagner \u00e0 l&#039;int\u00e9rieur en confort et en qualit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La direction est pr\u00e9cise et rend la conduite intuitive et s\u00fbre. Il dispose d&#039;un double mode de fonctionnement inclus dans la bo\u00eete de vitesses, comme le mode traditionnel D pour avancer et le mode B qui agit comme une seule p\u00e9dale, intensifiant la r\u00e9tention du moteur au rel\u00e2chement de l&#039;acc\u00e9l\u00e9rateur et rendant inutile l&#039;utilisation de la p\u00e9dale de frein. n\u00e9cessaire, sauf lors des freinages les plus intenses.<\/p>","protected":false},"excerpt":{"rendered":"<p>Renault Zoe ha sido, claramente, el veh\u00edculo el\u00e9ctrico m\u00e1s vendido en Europa durante el primer semestre del 2020, superando modelos tan bien valorados como el Tesla Model 3 o el e-Golf de Volkswagen. Su precio es de 30.000 euros y tiene una autonom\u00eda de casi 400 km, posicion\u00e1ndose como uno de los modelos de referencia&#8230;<\/p>","protected":false},"author":1,"featured_media":1843,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[68],"tags":[95,98,100,455,364],"class_list":["post-2012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coche-eletrico","tag-coche-electrico","tag-eficiencia-energetica","tag-movilidad-electrica","tag-renault-zoe","tag-vehiculo-electrico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa? - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa? - Armengol\" \/>\n<meta property=\"og:description\" content=\"Renault Zoe ha sido, claramente, el veh\u00edculo el\u00e9ctrico m\u00e1s vendido en Europa durante el primer semestre del 2020, superando modelos tan bien valorados como el Tesla Model 3 o el e-Golf de Volkswagen. Su precio es de 30.000 euros y tiene una autonom\u00eda de casi 400 km, posicion\u00e1ndose como uno de los modelos de referencia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-28T07:59:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T11:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa?\",\"datePublished\":\"2020-07-28T07:59:38+00:00\",\"dateModified\":\"2024-01-24T11:20:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/\"},\"wordCount\":501,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/renault-zoe.jpg\",\"keywords\":[\"Coche el\u00e9ctrico\",\"eficiencia energ\u00e9tica\",\"movilidad el\u00e9ctrica\",\"Renault Zoe\",\"veh\u00edculo el\u00e9ctrico\"],\"articleSection\":[\"Coche el\u00e9trico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/\",\"name\":\"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa? - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/renault-zoe.jpg\",\"datePublished\":\"2020-07-28T07:59:38+00:00\",\"dateModified\":\"2024-01-24T11:20:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/renault-zoe.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/renault-zoe.jpg\",\"width\":640,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa? - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa? - Armengol","og_description":"Renault Zoe ha sido, claramente, el veh\u00edculo el\u00e9ctrico m\u00e1s vendido en Europa durante el primer semestre del 2020, superando modelos tan bien valorados como el Tesla Model 3 o el e-Golf de Volkswagen. Su precio es de 30.000 euros y tiene una autonom\u00eda de casi 400 km, posicion\u00e1ndose como uno de los modelos de referencia...","og_url":"https:\/\/napoleon-armengol.com\/fr\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/","og_site_name":"Armengol","article_published_time":"2020-07-28T07:59:38+00:00","article_modified_time":"2024-01-24T11:20:44+00:00","og_image":[{"width":640,"height":600,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa?","datePublished":"2020-07-28T07:59:38+00:00","dateModified":"2024-01-24T11:20:44+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/"},"wordCount":501,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg","keywords":["Coche el\u00e9ctrico","eficiencia energ\u00e9tica","movilidad el\u00e9ctrica","Renault Zoe","veh\u00edculo el\u00e9ctrico"],"articleSection":["Coche el\u00e9trico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/","url":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/","name":"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa? - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg","datePublished":"2020-07-28T07:59:38+00:00","dateModified":"2024-01-24T11:20:44+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg","width":640,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/cual-es-el-coche-electrico-que-bate-records-de-ventas-en-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1l es el coche el\u00e9ctrico que bate r\u00e9cords de ventas en Europa?"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":68,"label":"Coche el\u00e9trico"}],"post_tag":[{"value":95,"label":"Coche el\u00e9ctrico"},{"value":98,"label":"eficiencia energ\u00e9tica"},{"value":100,"label":"movilidad el\u00e9ctrica"},{"value":455,"label":"Renault Zoe"},{"value":364,"label":"veh\u00edculo el\u00e9ctrico"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2020\/07\/renault-zoe.jpg",640,600,false],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":68,"name":"Coche el\u00e9trico","slug":"coche-eletrico","term_group":0,"term_taxonomy_id":68,"taxonomy":"category","description":"","parent":0,"count":63,"filter":"raw","term_order":"0","cat_ID":68,"category_count":63,"category_description":"","cat_name":"Coche el\u00e9trico","category_nicename":"coche-eletrico","category_parent":0}],"tag_info":[{"term_id":95,"name":"Coche el\u00e9ctrico","slug":"coche-electrico","term_group":0,"term_taxonomy_id":95,"taxonomy":"post_tag","description":"","parent":0,"count":45,"filter":"raw","term_order":"0"},{"term_id":98,"name":"eficiencia energ\u00e9tica","slug":"eficiencia-energetica","term_group":0,"term_taxonomy_id":98,"taxonomy":"post_tag","description":"","parent":0,"count":36,"filter":"raw","term_order":"0"},{"term_id":100,"name":"movilidad el\u00e9ctrica","slug":"movilidad-electrica","term_group":0,"term_taxonomy_id":100,"taxonomy":"post_tag","description":"","parent":0,"count":41,"filter":"raw","term_order":"0"},{"term_id":455,"name":"Renault Zoe","slug":"renault-zoe","term_group":0,"term_taxonomy_id":455,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"},{"term_id":364,"name":"veh\u00edculo el\u00e9ctrico","slug":"vehiculo-electrico","term_group":0,"term_taxonomy_id":364,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/2012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=2012"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/2012\/revisions"}],"predecessor-version":[{"id":2270,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/2012\/revisions\/2270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/1843"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=2012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=2012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=2012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}