{"id":2043,"date":"2022-04-13T10:50:47","date_gmt":"2022-04-13T10:50:47","guid":{"rendered":"https:\/\/blog-napoleon-armengol.com\/?p=884"},"modified":"2024-01-24T12:17:18","modified_gmt":"2024-01-24T11:17:18","slug":"para-que-sirve-el-tubo-para-cable-electrico","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/para-que-sirve-el-tubo-para-cable-electrico\/","title":{"rendered":"A quoi sert le tube du c\u00e2ble \u00e9lectrique ?"},"content":{"rendered":"<p style=\"text-align: justify\">Dans l&#039;article d&#039;aujourd&#039;hui, nous allons vous parler des types, des utilit\u00e9s et des particularit\u00e9s <a href=\"https:\/\/napoleon-armengol.com\/fr\/productos.php\/?lg=esp\">du <strong>tube de c\u00e2ble \u00e9lectrique<\/strong><\/a>.<\/p>\n<p style=\"text-align: justify\">Ce tube a une forme cylindrique et est g\u00e9n\u00e9ralement en plastique ou en m\u00e9tal et est utilis\u00e9 pour cacher et prot\u00e9ger les installations \u00e9lectriques d&#039;une construction, passant normalement par l&#039;int\u00e9rieur des murs et sortant par la sortie.<\/p>\n<p style=\"text-align: justify\">Il <strong>tube de c\u00e2ble \u00e9lectrique<\/strong> fait r\u00e9f\u00e9rence aux cylindres dans lesquels le c\u00e2blage est ins\u00e9r\u00e9 pour rendre une installation \u00e9lectrique plus r\u00e9sistante et s\u00fbre et \u00e9galement pour am\u00e9liorer l&#039;esth\u00e9tique en r\u00e9duisant l&#039;impact visuel. Ces tubes permettent d&#039;optimiser le trajet entre les c\u00e2bles pour mieux planifier l&#039;installation et les tubes en PVC sont normalement utilis\u00e9s au niveau domestique, mais pour les b\u00e2timents, usines, industries ou entreprises, on utilise g\u00e9n\u00e9ralement des tubes m\u00e9talliques, car ils ont plus de c\u00e2bles et plus de volts. . En fonction de la quantit\u00e9 de c\u00e2ble, l&#039;\u00e9paisseur du tube d\u00e9pendra \u00e9galement.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-833 size-full\" src=\"https:\/\/blog-napoleon-armengol.com\/wp-content\/uploads\/2021\/08\/electric-4198293_1920.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/p>\n<p style=\"text-align: justify\">Concernant le diam\u00e8tre, la taille de la construction, l&#039;\u00e9paisseur ou le nombre de c\u00e2bles sont pris en compte, ainsi que les caract\u00e9ristiques des tubes et la fonction du <strong>tube de c\u00e2ble \u00e9lectrique<\/strong> est de r\u00e9aliser une installation \u00e9lectrique s\u00fbre et de prot\u00e9ger l&#039;int\u00e9grit\u00e9 du c\u00e2blage, en \u00e9vitant toute menace ext\u00e9rieure, telle que l&#039;oxydation, l&#039;usure ou la d\u00e9t\u00e9rioration caus\u00e9e par la temp\u00eate.<\/p>\n<p style=\"text-align: justify\">Gr\u00e2ce \u00e0 l&#039;utilisation de ces tubes, on obtient une plus grande s\u00e9curit\u00e9 et plus d&#039;ordre dans le c\u00e2blage.<\/p>\n<h2 style=\"text-align: justify\">Types de tube pour c\u00e2ble \u00e9lectrique<\/h2>\n<p style=\"text-align: justify\">Vous pouvez trouver de nombreux types de <strong>tube de c\u00e2ble \u00e9lectrique<\/strong> et nous allons les expliquer ci-dessous :<\/p>\n<ul style=\"text-align: justify\">\n<li>M\u00e9tallique; Les mat\u00e9riaux que l&#039;on trouve habituellement sont le fer, l&#039;acier ou l&#039;aluminium.<\/li>\n<li>Non m\u00e9tallique\u00a0; Il s\u2019agit g\u00e9n\u00e9ralement de tuyaux en PVC, thermoplastique ou poly\u00e9thyl\u00e8ne.<\/li>\n<li>Compos\u00e9s\u00a0; Dans ce cas, il s\u2019agit de tubes fabriqu\u00e9s avec des mat\u00e9riaux m\u00e9talliques et non m\u00e9talliques, mais ils sont g\u00e9n\u00e9ralement plus chers.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Les types de c\u00e2bles peuvent \u00e9galement \u00eatre class\u00e9s en fonction de leur flexibilit\u00e9, puisqu&#039;il s&#039;agit d&#039;une caract\u00e9ristique tr\u00e8s importante pour joindre les coins des murs. Selon la flexibilit\u00e9, nous pouvons les classer en\u00a0:<\/p>\n<ul style=\"text-align: justify\">\n<li>tubes rigides; Ceux qui n\u00e9cessitent des joints sp\u00e9ciaux pour les coins des murs et sont g\u00e9n\u00e9ralement utilis\u00e9s dans les usines et \u00e0 l&#039;ext\u00e9rieur des murs.<\/li>\n<li>Tubes flexibles\u00a0; Ce sont des tubes en plastique ou en mat\u00e9riaux non m\u00e9talliques et sont flexibles, bien qu&#039;ils ne se plient pas compl\u00e8tement. Les connexions sont utilis\u00e9es dans les coins des murs et les tuyaux passent \u00e0 l&#039;int\u00e9rieur des murs<\/li>\n<li>Tubes pliables : Ce sont des tubes qui peuvent \u00eatre compl\u00e8tement pli\u00e9s et sont utilis\u00e9s pour les murs pr\u00e9fabriqu\u00e9s.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Les installations peuvent \u00eatre de diff\u00e9rents types, depuis des tubes fixes dans le mur ou le plafond jusqu&#039;\u00e0 un assemblage de tubes a\u00e9riens, des tubes de c\u00e2bles \u00e9lectriques encastr\u00e9s ou encore l&#039;enfouissement de tubes de c\u00e2bles \u00e9lectriques.<\/p>","protected":false},"excerpt":{"rendered":"<p>En el art\u00edculo de hoy vamos a hablarte de los tipos, utilidades y particularidades del tubo para cable el\u00e9ctrico. Este tubo tiene forma cil\u00edndrica y suele ser de pl\u00e1stico o de metal y se utiliza para ocultar y proteger las instalaciones el\u00e9ctricas en una construcci\u00f3n pasando, normalmente, por el interior de paredes y saliendo por&#8230;<\/p>","protected":false},"author":1,"featured_media":1885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[119],"tags":[71],"class_list":["post-2043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnico","tag-tubo-para-cable-electrico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico? - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/para-que-sirve-el-tubo-para-cable-electrico\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico? - Armengol\" \/>\n<meta property=\"og:description\" content=\"En el art\u00edculo de hoy vamos a hablarte de los tipos, utilidades y particularidades del tubo para cable el\u00e9ctrico. Este tubo tiene forma cil\u00edndrica y suele ser de pl\u00e1stico o de metal y se utiliza para ocultar y proteger las instalaciones el\u00e9ctricas en una construcci\u00f3n pasando, normalmente, por el interior de paredes y saliendo por...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/para-que-sirve-el-tubo-para-cable-electrico\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-13T10:50:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T11:17:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1060\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico?\",\"datePublished\":\"2022-04-13T10:50:47+00:00\",\"dateModified\":\"2024-01-24T11:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/\"},\"wordCount\":509,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/tubo-cable-electrico.jpg\",\"keywords\":[\"Tubo para cable el\u00e9ctrico\"],\"articleSection\":[\"T\u00e9cnico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/\",\"name\":\"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico? - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/tubo-cable-electrico.jpg\",\"datePublished\":\"2022-04-13T10:50:47+00:00\",\"dateModified\":\"2024-01-24T11:17:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/tubo-cable-electrico.jpg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/tubo-cable-electrico.jpg\",\"width\":1060,\"height\":795},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/para-que-sirve-el-tubo-para-cable-electrico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico? - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/para-que-sirve-el-tubo-para-cable-electrico\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico? - Armengol","og_description":"En el art\u00edculo de hoy vamos a hablarte de los tipos, utilidades y particularidades del tubo para cable el\u00e9ctrico. Este tubo tiene forma cil\u00edndrica y suele ser de pl\u00e1stico o de metal y se utiliza para ocultar y proteger las instalaciones el\u00e9ctricas en una construcci\u00f3n pasando, normalmente, por el interior de paredes y saliendo por...","og_url":"https:\/\/napoleon-armengol.com\/fr\/para-que-sirve-el-tubo-para-cable-electrico\/","og_site_name":"Armengol","article_published_time":"2022-04-13T10:50:47+00:00","article_modified_time":"2024-01-24T11:17:18+00:00","og_image":[{"width":1060,"height":795,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico?","datePublished":"2022-04-13T10:50:47+00:00","dateModified":"2024-01-24T11:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/"},"wordCount":509,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico.jpg","keywords":["Tubo para cable el\u00e9ctrico"],"articleSection":["T\u00e9cnico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/","url":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/","name":"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico? - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico.jpg","datePublished":"2022-04-13T10:50:47+00:00","dateModified":"2024-01-24T11:17:18+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico.jpg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico.jpg","width":1060,"height":795},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/para-que-sirve-el-tubo-para-cable-electrico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPara qu\u00e9 sirve el tubo para cable el\u00e9ctrico?"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":119,"label":"T\u00e9cnico"}],"post_tag":[{"value":71,"label":"Tubo para cable el\u00e9ctrico"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2022\/04\/tubo-cable-electrico-1024x768.jpg",1024,768,true],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":119,"name":"T\u00e9cnico","slug":"tecnico","term_group":0,"term_taxonomy_id":119,"taxonomy":"category","description":"","parent":0,"count":30,"filter":"raw","term_order":"0","cat_ID":119,"category_count":30,"category_description":"","cat_name":"T\u00e9cnico","category_nicename":"tecnico","category_parent":0}],"tag_info":[{"term_id":71,"name":"Tubo para cable el\u00e9ctrico","slug":"tubo-para-cable-electrico","term_group":0,"term_taxonomy_id":71,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/2043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=2043"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/2043\/revisions"}],"predecessor-version":[{"id":2232,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/2043\/revisions\/2232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/1885"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=2043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=2043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=2043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}