{"id":984,"date":"2023-03-27T11:06:28","date_gmt":"2023-03-27T11:06:28","guid":{"rendered":"https:\/\/blog-napoleon-armengol.com\/?p=984"},"modified":"2024-01-24T11:55:51","modified_gmt":"2024-01-24T10:55:51","slug":"984-2","status":"publish","type":"post","link":"https:\/\/napoleon-armengol.com\/fr\/984-2\/","title":{"rendered":"Le tube \u00e9lectrique m\u00e9tallique, un produit aux multiples applications\u00a0"},"content":{"rendered":"<p><span data-contrast=\"none\">Il <\/span><a href=\"https:\/\/blog-napoleon-armengol.com\/\"><b><span data-contrast=\"none\">tube \u00e9lectrique m\u00e9tallique<\/span><\/b><\/a><span data-contrast=\"none\"> C&#039;est un type de tube utilis\u00e9 dans l&#039;industrie pour une grande vari\u00e9t\u00e9 d&#039;applications. Ces tubes sont en m\u00e9tal et sont utilis\u00e9s pour prot\u00e9ger et transporter les c\u00e2bles \u00e9lectriques et autres composants dans diff\u00e9rents environnements. Ce sont des tubes qui poss\u00e8dent une s\u00e9rie de propri\u00e9t\u00e9s uniques, qui les rendent id\u00e9aux pour une utilisation dans des applications industrielles.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">L\u2019une des principales propri\u00e9t\u00e9s du tube \u00e9lectrique m\u00e9tallique est sa r\u00e9sistance. Ce sont des tubes con\u00e7us pour r\u00e9sister \u00e0 des conditions extr\u00eames, telles que des temp\u00e9ratures \u00e9lev\u00e9es, la corrosion et les vibrations. Cela les rend id\u00e9aux pour une utilisation dans des environnements industriels difficiles tels que les usines chimiques, les raffineries de p\u00e9trole et les usines chimiques.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Une autre propri\u00e9t\u00e9 importante de <\/span><b><span data-contrast=\"none\">tube \u00e9lectrique m\u00e9tallique<\/span><\/b><span data-contrast=\"none\"> est sa durabilit\u00e9. Ces tubes sont con\u00e7us pour r\u00e9sister \u00e0 l&#039;usure quotidienne, ce qui les rend id\u00e9aux pour une utilisation dans des applications de haute intensit\u00e9. Ils r\u00e9sistent \u00e9galement aux chocs et \u00e0 la d\u00e9formation, ce qui en fait la solution la plus adapt\u00e9e aux applications impliquant la manipulation et le transport de composants.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">En plus de leur r\u00e9sistance et de leur durabilit\u00e9, les tubes \u00e9lectriques m\u00e9talliques sont \u00e9galement tr\u00e8s polyvalents. Ces tubes sont disponibles dans une grande vari\u00e9t\u00e9 de tailles et de formes, afin de pouvoir s&#039;adapter \u00e0 tous types de besoins. Afin d&#039;offrir le maximum de garanties, il est important de faire confiance \u00e0 une entreprise sp\u00e9cialis\u00e9e dans ce type de produits comme nous le faisons chez Napole\u00f3n Armengol.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h2>Tube \u00e9lectrique m\u00e9tallique, une option tr\u00e8s s\u00e9curitaire pour tous types d&#039;applications<\/h2>\n<p><span data-contrast=\"none\">Les tubes \u00e9lectriques m\u00e9talliques sont \u00e9galement tr\u00e8s s\u00fbrs, car ils sont con\u00e7us pour r\u00e9pondre aux normes de s\u00e9curit\u00e9 et de qualit\u00e9, ce qui les rend id\u00e9aux pour une utilisation dans des applications impliquant la manipulation de composants \u00e9lectriques. Les tubes \u00e9lectriques m\u00e9talliques sont r\u00e9sistants au feu et ont une faible conductivit\u00e9 \u00e9lectrique, ce qui les rend s\u00fbrs pour une utilisation dans des environnements impliquant la manipulation de composants \u00e9lectriques et \u00e9lectroniques.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">En r\u00e9sum\u00e9, les tubes \u00e9lectriques m\u00e9talliques constituent une excellente option pour une utilisation dans les applications industrielles et pr\u00e9sentent une grande durabilit\u00e9, polyvalence et s\u00e9curit\u00e9. Si vous recherchez un tube de haute qualit\u00e9 pour votre projet industriel, le <\/span><b><span data-contrast=\"none\">tube \u00e9lectrique m\u00e9tallique<\/span><\/b><span data-contrast=\"none\">, peut devenir votre meilleure solution.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1020\" src=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/08\/123-53.jpg\" alt=\"tubo r\u00edgido\" width=\"2000\" height=\"1414\" \/><\/h2>\n<h2>Napol\u00e9on Armengol, sp\u00e9cialiste des syst\u00e8mes de tubes rigides<\/h2>\n<p>Napol\u00e9on Armengol s&#039;est impos\u00e9 comme une marque reconnue sur le march\u00e9 pour son engagement envers l&#039;excellence dans la production et pour son innovation constante dans la conception de nouveaux produits. Nous disposons d&#039;une large gamme de produits et tous se caract\u00e9risent par leur sp\u00e9cialisation, leur s\u00e9curit\u00e9 et leur durabilit\u00e9.<\/p>\n<p>Contactez-nous pour d\u00e9couvrir tout ce que nous pouvons offrir \u00e0 votre secteur ou entreprise. Chez Napol\u00e9on Armengol, nous vous aiderons \u00e0 trouver le meilleur produit pour chaque type de besoin qui se pr\u00e9sente.<\/p>","protected":false},"excerpt":{"rendered":"<p>El tubo el\u00e9ctrico met\u00e1lico es un tipo de tubo utilizado en la industria, para una gran variedad de aplicaciones. Estos tubos est\u00e1n hechos de metal y se utilizan para proteger y transportar cables el\u00e9ctricos y otros componentes en diferentes entornos. Son tubos que tienen una serie de propiedades \u00fanicas, que los hacen ideales para su&#8230;<\/p>","protected":false},"author":1,"featured_media":1881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[119],"tags":[87],"class_list":["post-984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnico","tag-tubo-electrico-metalico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0 - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/984-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0 - Armengol\" \/>\n<meta property=\"og:description\" content=\"El tubo el\u00e9ctrico met\u00e1lico es un tipo de tubo utilizado en la industria, para una gran variedad de aplicaciones. Estos tubos est\u00e1n hechos de metal y se utilizan para proteger y transportar cables el\u00e9ctricos y otros componentes en diferentes entornos. Son tubos que tienen una serie de propiedades \u00fanicas, que los hacen ideales para su...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/984-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T11:06:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T10:55:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1063\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\"},\"headline\":\"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0\",\"datePublished\":\"2023-03-27T11:06:28+00:00\",\"dateModified\":\"2024-01-24T10:55:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/\"},\"wordCount\":521,\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg\",\"keywords\":[\"tubo el\u00e9ctrico met\u00e1lico\"],\"articleSection\":[\"T\u00e9cnico\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/\",\"name\":\"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0 - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg\",\"datePublished\":\"2023-03-27T11:06:28+00:00\",\"dateModified\":\"2024-01-24T10:55:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg\",\"width\":1063,\"height\":1600,\"caption\":\"sistemas de tubo r\u00edgido\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/984-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/person\\\/e558fc54676c8886a95c89646b733a67\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/napoleon-armengol.com\"],\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/fr\\\/author\\\/admin_5wnh1vf4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0 - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/984-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0 - Armengol","og_description":"El tubo el\u00e9ctrico met\u00e1lico es un tipo de tubo utilizado en la industria, para una gran variedad de aplicaciones. Estos tubos est\u00e1n hechos de metal y se utilizan para proteger y transportar cables el\u00e9ctricos y otros componentes en diferentes entornos. Son tubos que tienen una serie de propiedades \u00fanicas, que los hacen ideales para su...","og_url":"https:\/\/napoleon-armengol.com\/fr\/984-2\/","og_site_name":"Armengol","article_published_time":"2023-03-27T11:06:28+00:00","article_modified_time":"2024-01-24T10:55:51+00:00","og_image":[{"width":1063,"height":1600,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/napoleon-armengol.com\/984-2\/#article","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/984-2\/"},"author":{"name":"admin","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67"},"headline":"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0","datePublished":"2023-03-27T11:06:28+00:00","dateModified":"2024-01-24T10:55:51+00:00","mainEntityOfPage":{"@id":"https:\/\/napoleon-armengol.com\/984-2\/"},"wordCount":521,"publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"image":{"@id":"https:\/\/napoleon-armengol.com\/984-2\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg","keywords":["tubo el\u00e9ctrico met\u00e1lico"],"articleSection":["T\u00e9cnico"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/984-2\/","url":"https:\/\/napoleon-armengol.com\/984-2\/","name":"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0 - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/984-2\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/984-2\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg","datePublished":"2023-03-27T11:06:28+00:00","dateModified":"2024-01-24T10:55:51+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/984-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/984-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/984-2\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25.jpeg","width":1063,"height":1600,"caption":"sistemas de tubo r\u00edgido"},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/984-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Tubo el\u00e9ctrico met\u00e1lico, un producto con muchas aplicaciones\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/person\/e558fc54676c8886a95c89646b733a67","name":"admin","sameAs":["http:\/\/napoleon-armengol.com"],"url":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"}]}},"taxonomy_info":{"category":[{"value":119,"label":"T\u00e9cnico"}],"post_tag":[{"value":87,"label":"tubo el\u00e9ctrico met\u00e1lico"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-28-at-11.14.25-680x1024.jpeg",680,1024,true],"author_info":{"display_name":"admin","author_link":"https:\/\/napoleon-armengol.com\/fr\/author\/admin_5wnh1vf4\/"},"comment_info":0,"category_info":[{"term_id":119,"name":"T\u00e9cnico","slug":"tecnico","term_group":0,"term_taxonomy_id":119,"taxonomy":"category","description":"","parent":0,"count":30,"filter":"raw","term_order":"0","cat_ID":119,"category_count":30,"category_description":"","cat_name":"T\u00e9cnico","category_nicename":"tecnico","category_parent":0}],"tag_info":[{"term_id":87,"name":"tubo el\u00e9ctrico met\u00e1lico","slug":"tubo-electrico-metalico","term_group":0,"term_taxonomy_id":87,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=984"}],"version-history":[{"count":1,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/984\/revisions"}],"predecessor-version":[{"id":2206,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/posts\/984\/revisions\/2206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/1881"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/categories?post=984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/tags?post=984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}