{"id":860,"date":"2023-05-17T09:51:32","date_gmt":"2023-05-17T09:51:32","guid":{"rendered":"http:\/\/napoleon-armengol.com\/?post_type=product&#038;p=860"},"modified":"2023-11-29T07:46:30","modified_gmt":"2023-11-29T07:46:30","slug":"racor-pa6-pg-para-tubo-flexible-negro","status":"publish","type":"product","link":"https:\/\/napoleon-armengol.com\/fr\/product\/racor-pa6-pg-para-tubo-flexible-negro\/","title":{"rendered":"RACCORD PA6 PG POUR TUBE FLEXIBLE NOIR"},"content":{"rendered":"<p>ESPECIFICACIONES T\u00c9CNICAS SEG\u00daN NORMA IEC 61386-23<\/p>\n<p><strong>Code<\/strong>: 244340680212.<br \/>\n<strong>Temp\u00e9rature d&#039;utilisation<\/strong>: -40\u00baC + 120\u00baC.<br \/>\n<strong>R\u00e9sistance \u00e0 la compression<\/strong>: &gt;320N.<br \/>\n<strong>Resistencia al impacto<\/strong>: 6J.<br \/>\n<strong>Aucun propagateur de la flamme.<\/strong><\/p>\n<p><strong>Mat\u00e9riel<\/strong>: Polyamide PA6 V2, sans halog\u00e8ne.<br \/>\n<strong>Couleur<\/strong>: Noir RAL 9005.<br \/>\n<strong>Auto-extinguible<\/strong>: V2 selon UL94.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1294 size-full alignnone\" src=\"http:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/certificados-1.png\" alt=\"\" width=\"600\" height=\"108\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>DIMENSIONS SELON LA NORME DIN 40430<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-720\" src=\"http:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO-1.png\" alt=\"\" width=\"2000\" height=\"622\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO-1.png 2000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO-1-300x93.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO-1-1024x318.png 1024w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO-1-768x239.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO-1-1536x478.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>","protected":false},"featured_media":633,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"product_cat":[19,21],"product_tag":[],"class_list":["post-860","product","type-product","status-publish","has-post-thumbnail","product_cat-sistema-de-tubo-flexible","product_cat-accesorios-tubo-flexible-pa6","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/product\/racor-pa6-pg-para-tubo-flexible-negro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO - Armengol\" \/>\n<meta property=\"og:description\" content=\"DIMENSIONES SEG\u00daN NORMA DIN 40430\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/product\/racor-pa6-pg-para-tubo-flexible-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T07:46:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/\",\"name\":\"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png\",\"datePublished\":\"2023-05-17T09:51:32+00:00\",\"dateModified\":\"2023-11-29T07:46:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/racor-pa6-pg-para-tubo-flexible-negro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/product\/racor-pa6-pg-para-tubo-flexible-negro\/","og_locale":"fr_FR","og_type":"article","og_title":"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO - Armengol","og_description":"DIMENSIONES SEG\u00daN NORMA DIN 40430","og_url":"https:\/\/napoleon-armengol.com\/fr\/product\/racor-pa6-pg-para-tubo-flexible-negro\/","og_site_name":"Armengol","article_modified_time":"2023-11-29T07:46:30+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/","url":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/","name":"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png","datePublished":"2023-05-17T09:51:32+00:00","dateModified":"2023-11-29T07:46:30+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/producto\/racor-pa6-pg-para-tubo-flexible-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/napoleon-armengol.com\/productos\/"},{"@type":"ListItem","position":3,"name":"RACOR PA6 PG PARA TUBO FLEXIBLE NEGRO"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":19,"label":"Sistema de tubo flexible"},{"value":21,"label":"Accesorios tubo flexible PA6"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/RACOR-PA6-PG-PARA-TUBO-FLEXIBLE-NEGRO.png",1000,1000,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product\/860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=860"}],"version-history":[{"count":2,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product\/860\/revisions"}],"predecessor-version":[{"id":1660,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product\/860\/revisions\/1660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/633"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=860"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product_cat?post=860"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product_tag?post=860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}