{"id":895,"date":"2023-05-18T08:14:54","date_gmt":"2023-05-18T08:14:54","guid":{"rendered":"http:\/\/napoleon-armengol.com\/?post_type=product&#038;p=895"},"modified":"2023-11-21T10:15:19","modified_gmt":"2023-11-21T10:15:19","slug":"molde-cable-t-vertical","status":"publish","type":"product","link":"https:\/\/napoleon-armengol.com\/fr\/product\/molde-cable-t-vertical\/","title":{"rendered":"MOULE \u00c0 C\u00c2BLE EN T VERTICAL"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-700\" src=\"http:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL.png\" alt=\"\" width=\"2000\" height=\"716\" srcset=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL.png 2000w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-300x107.png 300w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1024x367.png 1024w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-768x275.png 768w, https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1536x550.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>","protected":false},"featured_media":786,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"product_cat":[37,41,42],"product_tag":[],"class_list":["post-895","product","type-product","status-publish","has-post-thumbnail","product_cat-material-toma-tierra","product_cat-soldadura-aluminotermica","product_cat-moldes","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MOLDE CABLE T VERTICAL - Armengol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/napoleon-armengol.com\/fr\/product\/molde-cable-t-vertical\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MOLDE CABLE T VERTICAL - Armengol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/napoleon-armengol.com\/fr\/product\/molde-cable-t-vertical\/\" \/>\n<meta property=\"og:site_name\" content=\"Armengol\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T10:15:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/\",\"name\":\"MOLDE CABLE T VERTICAL - Armengol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MOLDE-CABLE-T-VERTICAL-1.png\",\"datePublished\":\"2023-05-18T08:14:54+00:00\",\"dateModified\":\"2023-11-21T10:15:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/#primaryimage\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MOLDE-CABLE-T-VERTICAL-1.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MOLDE-CABLE-T-VERTICAL-1.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/producto\\\/molde-cable-t-vertical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/napoleon-armengol.com\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MOLDE CABLE T VERTICAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#website\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"name\":\"Armengol\",\"description\":\"Seguridad y especializaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/napoleon-armengol.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#organization\",\"name\":\"Armengol\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"contentUrl\":\"https:\\\/\\\/napoleon-armengol.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGO-ARMENGOL.png\",\"width\":460,\"height\":81,\"caption\":\"Armengol\"},\"image\":{\"@id\":\"https:\\\/\\\/napoleon-armengol.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MOLDE CABLE T VERTICAL - Armengol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/napoleon-armengol.com\/fr\/product\/molde-cable-t-vertical\/","og_locale":"fr_FR","og_type":"article","og_title":"MOLDE CABLE T VERTICAL - Armengol","og_url":"https:\/\/napoleon-armengol.com\/fr\/product\/molde-cable-t-vertical\/","og_site_name":"Armengol","article_modified_time":"2023-11-21T10:15:19+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/","url":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/","name":"MOLDE CABLE T VERTICAL - Armengol","isPartOf":{"@id":"https:\/\/napoleon-armengol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/#primaryimage"},"image":{"@id":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/#primaryimage"},"thumbnailUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1.png","datePublished":"2023-05-18T08:14:54+00:00","dateModified":"2023-11-21T10:15:19+00:00","breadcrumb":{"@id":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/#primaryimage","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/napoleon-armengol.com\/producto\/molde-cable-t-vertical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/napoleon-armengol.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/napoleon-armengol.com\/productos\/"},{"@type":"ListItem","position":3,"name":"MOLDE CABLE T VERTICAL"}]},{"@type":"WebSite","@id":"https:\/\/napoleon-armengol.com\/#website","url":"https:\/\/napoleon-armengol.com\/","name":"Armengol","description":"Seguridad y especializaci\u00f3n","publisher":{"@id":"https:\/\/napoleon-armengol.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/napoleon-armengol.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/napoleon-armengol.com\/#organization","name":"Armengol","url":"https:\/\/napoleon-armengol.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/","url":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","contentUrl":"https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/04\/LOGO-ARMENGOL.png","width":460,"height":81,"caption":"Armengol"},"image":{"@id":"https:\/\/napoleon-armengol.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":37,"label":"Material toma tierra"},{"value":41,"label":"Soldadura aluminot\u00e9rmica"},{"value":42,"label":"Moldes"}]},"featured_image_src_large":["https:\/\/napoleon-armengol.com\/wp-content\/uploads\/2023\/05\/MOLDE-CABLE-T-VERTICAL-1.png",1000,1000,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product\/895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/comments?post=895"}],"version-history":[{"count":0,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product\/895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media\/786"}],"wp:attachment":[{"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/media?parent=895"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product_cat?post=895"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/napoleon-armengol.com\/fr\/wp-json\/wp\/v2\/product_tag?post=895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}